{"id":40454,"date":"2023-06-05T10:00:28","date_gmt":"2023-06-05T01:00:28","guid":{"rendered":"https:\/\/de.meviy.misumi-ec.com\/help\/sin-categorizar\/40454\/"},"modified":"2025-11-04T14:33:53","modified_gmt":"2025-11-04T05:33:53","slug":"%e8%a8%ad%e8%a8%88%e5%8e%9f%e7%82%b9%e3%82%92%e5%a4%89%e6%9b%b4%e3%81%99%e3%82%8b-2","status":"publish","type":"post","link":"https:\/\/de.meviy.misumi-ec.com\/help\/es\/operation_manual-es-c\/tup_configuration-es-c\/40454\/","title":{"rendered":"Cambiar el origen de un dise\u00f1o"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"40454\" class=\"elementor elementor-40454 elementor-26068\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9154916 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9154916\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0da9642\" data-id=\"0da9642\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-99570fd elementor-widget elementor-widget-text-editor\" data-id=\"99570fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Si no se especifica, se utilizar\u00e1 el origen (el icono [ICON] en el modelo <img decoding=\"async\" class=\"alignnone wp-image-5342\" src=\"\/help\/wp-content\/uploads\/2023\/08\/26068_02_deEN.png\" alt=\"\" width=\"22\" height=\"20\" \/> ) como referencia de mecanizado y se garantizar\u00e1n las tolerancias generales. Se garantizar\u00e1n la referencia de mecanizado y las tolerancias generales.<\/li><li>En la plataforma meviy, el origen es el punto de intersecci\u00f3n entre la superficie izquierda y el eje central. El origen se puede cambiar al punto de intersecci\u00f3n entre la superficie izquierda o derecha y el eje central.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9638de8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9638de8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-52d2831\" data-id=\"52d2831\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7815d97 enlarged elementor-widget elementor-widget-image\" data-id=\"7815d97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1600\" height=\"900\" src=\"https:\/\/de.meviy.misumi-ec.com\/help\/wp-content\/uploads\/2023\/06\/40454_01_deES.png\" class=\"attachment-full size-full wp-image-80016\" alt=\"\" srcset=\"https:\/\/de.meviy.misumi-ec.com\/help\/wp-content\/uploads\/2023\/06\/40454_01_deES.png 1600w, https:\/\/de.meviy.misumi-ec.com\/help\/wp-content\/uploads\/2023\/06\/40454_01_deES-300x169.png 300w, https:\/\/de.meviy.misumi-ec.com\/help\/wp-content\/uploads\/2023\/06\/40454_01_deES-1024x576.png 1024w, https:\/\/de.meviy.misumi-ec.com\/help\/wp-content\/uploads\/2023\/06\/40454_01_deES-768x432.png 768w, https:\/\/de.meviy.misumi-ec.com\/help\/wp-content\/uploads\/2023\/06\/40454_01_deES-1536x864.png 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f7dc35b\" data-id=\"f7dc35b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14d4373 elementor-widget elementor-widget-text-editor\" data-id=\"14d4373\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol style=\"list-style-type: decimal; margin-left: 1.5em;\">\n \t<li style=\"font-weight: bold;\">Haga clic en <img decoding=\"async\" src=\"\/help\/wp-content\/uploads\/2021\/02\/toolbar_7_c.png\" alt=\"\" width=\"32\" \/>.\n<span style=\"font-weight: normal;\">Las \u00e1reas a las que se puede mover el punto de origen se resaltar\u00e1n en azul claro.<\/span><\/li>\n \t<li style=\"font-weight: bold;\">Seleccione la ubicaci\u00f3n a la que desea mover el punto de origen.\n<span style=\"font-weight: normal;\">El lugar al que mueva el punto de origen se utilizar\u00e1 como referencia de mecanizado y se garantizar\u00e1n las tolerancias generales.<\/span><\/li>\n<\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Si no se especifica, se utilizar\u00e1 el origen (el icono [ICON] en el modelo ) como referencia de mecanizado y se garantizar\u00e1n las tolerancias generales. Se garantizar\u00e1n la referencia de mecanizado y las tolerancias generales. En la plataforma meviy, el origen es el punto de intersecci\u00f3n entre la superficie izquierda y el eje central. El origen se puede cambiar al punto de intersecci\u00f3n entre la superficie izquierda o derecha y el eje central. Haga clic en . Las \u00e1reas a las que se puede mover el punto de origen se resaltar\u00e1n en azul claro. Seleccione la ubicaci\u00f3n a la que desea mover el punto de origen. El lugar al que [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[306],"tags":[307],"class_list":["post-40454","post","type-post","status-publish","format-standard","hentry","category-tup_configuration-es-c","tag-manual_tup-es"],"views":5,"_links":{"self":[{"href":"https:\/\/de.meviy.misumi-ec.com\/help\/es\/wp-json\/wp\/v2\/posts\/40454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/de.meviy.misumi-ec.com\/help\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/de.meviy.misumi-ec.com\/help\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/de.meviy.misumi-ec.com\/help\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/de.meviy.misumi-ec.com\/help\/es\/wp-json\/wp\/v2\/comments?post=40454"}],"version-history":[{"count":14,"href":"https:\/\/de.meviy.misumi-ec.com\/help\/es\/wp-json\/wp\/v2\/posts\/40454\/revisions"}],"predecessor-version":[{"id":112153,"href":"https:\/\/de.meviy.misumi-ec.com\/help\/es\/wp-json\/wp\/v2\/posts\/40454\/revisions\/112153"}],"wp:attachment":[{"href":"https:\/\/de.meviy.misumi-ec.com\/help\/es\/wp-json\/wp\/v2\/media?parent=40454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/de.meviy.misumi-ec.com\/help\/es\/wp-json\/wp\/v2\/categories?post=40454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/de.meviy.misumi-ec.com\/help\/es\/wp-json\/wp\/v2\/tags?post=40454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}