{"id":39856,"date":"2021-02-02T13:06:02","date_gmt":"2021-02-02T04:06:02","guid":{"rendered":"https:\/\/de.meviy.misumi-ec.com\/help\/non-categorizzato\/39856\/"},"modified":"2025-12-19T12:53:28","modified_gmt":"2025-12-19T03:53:28","slug":"%e7%b2%be%e5%ba%a6%e7%a9%b4%e3%82%bf%e3%83%83%e3%83%97%e7%a9%b4-%e3%82%a4%e3%83%b3%e3%82%b5%e3%83%bc%e3%83%88%e7%a9%b4-1%e6%ae%b5%e7%a9%b4-2%e6%ae%b5%e7%a9%b4","status":"publish","type":"post","link":"https:\/\/de.meviy.misumi-ec.com\/help\/it\/technical_info-it-c\/mpb_conditions-it-c\/39856\/","title":{"rendered":"Standard per diversi tipi di fori e tasche"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"39856\" class=\"elementor elementor-39856 elementor-9726\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c54749e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c54749e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6f8d5c0\" data-id=\"6f8d5c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7519ef elementor-widget elementor-widget-text-editor\" data-id=\"d7519ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul style=\"font-size: 100%;\">\n \t<li style=\"display: block; float: left; margin-right: 1em;\"><a href=\"#box_1\">Fori cilindrici<\/a>\u3000|<\/li>\n \t<li style=\"display: block; float: left; margin-right: 1em;\"><a href=\"#box_2\">Intervalli di precisione quotabili automaticamente<\/a>\u00a0 |<\/li>\n \t<li style=\"display: block; float: left; margin-right: 1em;\"><a href=\"#box_3\">Fori filettati<\/a>\u00a0 |<\/li>\n \t<li style=\"display: block; float: left; margin-right: 1em;\"><a href=\"#box_4\">Fori con inserto<\/a>\u00a0 |<\/li>\n \t<li style=\"display: block; float: left; margin-right: 1em;\"><a href=\"#box_5\">Fori a 1 scalino<\/a>\u00a0 |<\/li>\n \t<li style=\"display: block; float: left; margin-right: 1em;\"><a href=\"#box_6\">Fori a 2 scalini<\/a>\u00a0 |<\/li>\n \t<li style=\"display: block; float: left; margin-right: 1em;\"><a href=\"#box_7\">Fori svasati<\/a>\u00a0 |<\/li>\n \t<li style=\"display: block; float: left; margin-right: 1em;\"><a href=\"#box_8\">Fori asolati<\/a>\u00a0 |<\/li>\n \t<li style=\"display: block; float: left; margin-right: 1em;\"><a href=\"#box_9\">Fori asolati di precisione<\/a>\u00a0 |<\/li>\n \t<li style=\"display: block; float: left; margin-right: 1em;\"><a href=\"#box_10\">Tasche<\/a><\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e8f9569 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e8f9569\" data-element_type=\"section\" data-e-type=\"section\" id=\"box_1\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e2c9f19\" data-id=\"e2c9f19\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5182fab elementor-widget elementor-widget-heading\" data-id=\"5182fab\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"box_1\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fori cilindrici<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0e8e0b elementor-widget elementor-widget-text-editor\" data-id=\"d0e8e0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I fori realizzati con punte o frese non soggetti a tolleranze di precisione specifiche sono denominati &#8220;fori cilindrici&#8221; nei servizi di lavorazione. Gli utensili utilizzati hanno differenti profondit\u00e0 di lavorazione preventivabili automaticamente.<\/p><p>Il valore massimo indicato \u00e8 da considerarsi approssimativo.<\/p><p><span style=\"color: #ff0000;\">Tale valore pu\u00f2 variare a seconda di altri fattori indicati in fase di preventivo, come geometria o materiale. Grazie per la comprensione.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0016bd4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0016bd4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b65f672\" data-id=\"b65f672\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f80e869 elementor-widget elementor-widget-heading\" data-id=\"f80e869\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Lavorazione con punta\n<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f83a1b4 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"f83a1b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\n\n<table class=\"tableHover_single mT0\">\n<tbody>\n<tr>\n<th colspan=\"2\">Acciaio, Acciaio pre-temprato e acciaio per utensili\n, alluminio, Acciaio inossidabile<\/th>\n<\/tr>\n<tr>\n<th>Diametro<\/th>\n<th>Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<\/tr>\n<tr>\n<th>1,0 \u2264 Diametro \u2264 1,9<\/th>\n<td>40<\/td>\n<\/tr>\n<tr>\n<th>2,0 \u2264 Diametro \u2264 3,2<\/th>\n<td>150<\/td>\n<\/tr>\n<tr>\n<th>3,3 \u2264 Diametro \u2264 4,2<\/th>\n<td>180<\/td>\n<\/tr>\n<tr>\n<th>4,3 \u2264 Diameter \u2264 6,9<\/th>\n<td>200<\/td>\n<\/tr>\n<tr>\n<th>7,0 \u2264 Diametro \u2264 9,9<\/th>\n<td>220<\/td>\n<\/tr>\n<tr>\n<th>10 \u2264 Diametro \u2264 20<\/th>\n<td>300<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2be2190 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2be2190\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d69f462\" data-id=\"d69f462\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40f7e79 elementor-widget elementor-widget-text-editor\" data-id=\"40f7e79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b02eb49 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"b02eb49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th colspan=\"2\">Resina<\/th>\n<\/tr>\n<tr>\n<th>Diametro<\/th>\n<th>Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<\/tr>\n<tr>\n<th>1,0 \u2264 Diametro \u2264 1,9 (incrementi di 0,1)<\/th>\n<td>\u2264 Diametro * 10<\/td>\n<\/tr>\n<tr>\n<th>2<\/th>\n<td>\u2264 Diametro * 15<\/td>\n<\/tr>\n<tr>\n<th>2,1 \u2264 Diametro \u2264 3,0 (incrementi di 0,1)<\/th>\n<td>\u2264 Diametro * 14<\/td>\n<\/tr>\n<tr>\n<th>3,1 \u2264 Diametro \u2264 4,2 (incrementi di 0,1)<\/th>\n<td>\u2264 Diametro * 13<\/td>\n<\/tr>\n<tr>\n<th>4,3 \u2264 Diametro \u2264 5,7 (incrementi di 0,1)<\/th>\n<td>\u2264 Diametro * 12<\/td>\n<\/tr>\n<tr>\n<th>5,8 \u2264 Diametro \u2264 6,8 (incrementi di 0,1)<\/th>\n<td>\u2264 Diametro * 11<\/td>\n<\/tr>\n<tr>\n<th>6,9 \u2264 Diametro \u2264 9,7 (incrementi di 0.1)<\/th>\n<td>\u2264 Diametro * 10<\/td>\n<\/tr>\n<tr>\n<th>9,8 \u2264 Diametro \u2264 13 (incrementi di 0,1)<\/th>\n<td>\u2264 Diametro * 9<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-01228b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"01228b3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2ccf191\" data-id=\"2ccf191\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a78eef1 elementor-widget elementor-widget-heading\" data-id=\"a78eef1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Lavorazione con fresa\n<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a5666e elementor-widget elementor-widget-text-editor\" data-id=\"2a5666e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tPer diametri che non prevedono l&#8217;uso della punta, la profondit\u00e0 di lavorazione \u00e8 la seguente:\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0fa855c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0fa855c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-97374d2\" data-id=\"97374d2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fdfa1ce elementor-widget elementor-widget-text-editor\" data-id=\"fdfa1ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aebcd86 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"aebcd86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th colspan=\"6\">Acciaio, Acciaio pre-temprato e acciaio per utensili<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center;\" colspan=\"2\">Diametro<\/th>\n<th rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<th style=\"ext-align: center;\" colspan=\"2\">Diametro<\/th>\n<th rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center;\">&gt;<\/th>\n<th style=\"text-align: center;\">\u2264<\/th>\n<th style=\"text-align: center;\">&gt;<\/th>\n<th style=\"text-align: center;\">\u2264<\/th>\n<\/tr>\n<tr>\n<th>2,999<\/th>\n<th>3,5<\/th>\n<td>\u226410<\/td>\n<th>9<\/th>\n<th>11<\/th>\n<td>\u226440<\/td>\n<\/tr>\n<tr>\n<th>3,5<\/th>\n<th>4,5<\/th>\n<td>\u226412<\/td>\n<th>11<\/th>\n<th>13<\/th>\n<td>\u226450<\/td>\n<\/tr>\n<tr>\n<th>4,5<\/th>\n<th>6<\/th>\n<td>\u226416<\/td>\n<th>13<\/th>\n<th>17<\/th>\n<td>\u226460<\/td>\n<\/tr>\n<tr>\n<th>6<\/th>\n<th>7<\/th>\n<td>\u226420<\/td>\n<th>17<\/th>\n<th>21<\/th>\n<td>\u226480<\/td>\n<\/tr>\n<tr>\n<th>7<\/th>\n<th>9<\/th>\n<td>\u226430<\/td>\n<th>21<\/th>\n<th>Nessuna restrizione<\/th>\n<td>\u2264100<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f177e00 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f177e00\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fde10e8\" data-id=\"fde10e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b17358c elementor-widget elementor-widget-text-editor\" data-id=\"b17358c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c66b0f9 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"c66b0f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th colspan=\"6\">Alluminio<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center;\" colspan=\"2\">Diametro<\/th>\n<th rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<th style=\"ext-align: center;\" colspan=\"2\">Diametro<\/th>\n<th rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center;\">&gt;<\/th>\n<th style=\"text-align: center;\">\u2264<\/th>\n<th style=\"text-align: center;\">&gt;<\/th>\n<th style=\"text-align: center;\">\u2264<\/th>\n<\/tr>\n<tr>\n<th>2,999<\/th>\n<th>3,5<\/th>\n<td>\u226410<\/td>\n<th>9<\/th>\n<th>11<\/th>\n<td>\u226440<\/td>\n<\/tr>\n<tr>\n<th>3,5<\/th>\n<th>4,5<\/th>\n<td>\u226412<\/td>\n<th>11<\/th>\n<th>13<\/th>\n<td>\u226450<\/td>\n<\/tr>\n<tr>\n<th>4,5<\/th>\n<th>6<\/th>\n<td>\u226416<\/td>\n<th>13<\/th>\n<th>17<\/th>\n<td>\u226460<\/td>\n<\/tr>\n<tr>\n<th>6<\/th>\n<th>7<\/th>\n<td>\u226425<\/td>\n<th>17<\/th>\n<th>21<\/th>\n<td>\u226480<\/td>\n<\/tr>\n<tr>\n<th>7<\/th>\n<th>9<\/th>\n<td>\u226430<\/td>\n<th>21<\/th>\n<th>Nessuna restrizione<\/th>\n<td>\u2264100<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e2d893f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e2d893f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-286ce02\" data-id=\"286ce02\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0fcbd08 elementor-widget elementor-widget-text-editor\" data-id=\"0fcbd08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff8c546 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"ff8c546\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th colspan=\"6\">Acciaio inossidabile<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center;\" colspan=\"2\">Diametro<\/th>\n<th rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<th style=\"ext-align: center;\" colspan=\"2\">Diametro<\/th>\n<th rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center;\">&gt;<\/th>\n<th style=\"text-align: center;\">\u2264<\/th>\n<th style=\"text-align: center;\">&gt;<\/th>\n<th style=\"text-align: center;\">\u2264<\/th>\n<\/tr>\n<tr>\n<th>2,999<\/th>\n<th>3,5<\/th>\n<td>\u226410<\/td>\n<th>9<\/th>\n<th>11<\/th>\n<td>\u226432<\/td>\n<\/tr>\n<tr>\n<th>3,5<\/th>\n<th>4,5<\/th>\n<td>\u226412<\/td>\n<th>11<\/th>\n<th>13<\/th>\n<td>\u226440<\/td>\n<\/tr>\n<tr>\n<th>4,5<\/th>\n<th>6<\/th>\n<td>\u226416<\/td>\n<th>13<\/th>\n<th>17<\/th>\n<td>\u226448<\/td>\n<\/tr>\n<tr>\n<th>6<\/th>\n<th>7<\/th>\n<td>\u226420<\/td>\n<th>17<\/th>\n<th>21<\/th>\n<td>\u226464<\/td>\n<\/tr>\n<tr>\n<th>7<\/th>\n<th>9<\/th>\n<td>\u226424<\/td>\n<th>21<\/th>\n<th>Nessuna restrizione<\/th>\n<td>\u226480<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f1084f3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f1084f3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3778b0a\" data-id=\"3778b0a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ac11d9 elementor-widget elementor-widget-text-editor\" data-id=\"7ac11d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d885003 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"d885003\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th style=\"width: 97.411%;\" colspan=\"6\">Resina<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center; width: 19.0939%;\" colspan=\"2\">Diametro<\/th>\n<th style=\"width: 28.9644%;\" rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<th style=\"width: 20.0647%;\" colspan=\"2\">Diametro<\/th>\n<th style=\"width: 29.288%;\" rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center; width: 11.165%;\">&gt;<\/th>\n<th style=\"text-align: center; width: 7.9288%;\">\u2264<\/th>\n<th style=\"text-align: center; width: 5.01618%;\">&gt;<\/th>\n<th style=\"text-align: center; width: 15.0485%;\">\u2264<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 11.165%;\">2,999<\/th>\n<th style=\"width: 7.9288%;\">3,5<\/th>\n<td>\u22647,5<\/td>\n<th style=\"width: 5.01618%;\">11<\/th>\n<th style=\"width: 15.0485%;\">13<\/th>\n<td style=\"width: 29.288%;\">\u226430<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 11.165%;\">3,5<\/th>\n<th style=\"width: 7.9288%;\">4,5<\/th>\n<td>\u226410<\/td>\n<th style=\"width: 5.01618%;\">13<\/th>\n<th style=\"width: 15.0485%;\">18<\/th>\n<td style=\"width: 29.288%;\">\u226440<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 11.165%;\">4,5<\/th>\n<th style=\"width: 7.9288%;\">7<\/th>\n<td>\u226415<\/td>\n<th style=\"width: 5.01618%;\">18<\/th>\n<th style=\"width: 15.0485%;\">Nessuna restrizione<\/th>\n<td style=\"width: 29.288%;\">\u226460<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 11.165%;\">7<\/th>\n<th style=\"width: 7.9288%;\">11<\/th>\n<td>\u226420<\/td>\n<th style=\"width: 49.3528%;\" colspan=\"3\">\u2013<\/th>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-252fa60 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"252fa60\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ae31a6\" data-id=\"1ae31a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7756199 elementor-widget elementor-widget-text-editor\" data-id=\"7756199\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c71010a tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"c71010a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th style=\"width: 97.4109%;\" colspan=\"6\">\n<ul>\n \t<li>Piatti lucidati<\/li>\n \t<li>(EN 1.0038 equiv. (barra piatta), EN 1.1191  equiv. (barra piatta), EN 1.4301  equiv. (barra piatta), EN AW-6063  equiv. (barra piatta))<\/li>\n<\/ul>\n<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center; width: 19.0938%;\" colspan=\"2\">Diametro<\/th>\n<th style=\"width: 28.9644%;\" rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<th style=\"width: 20.0647%;\" colspan=\"2\">Diametro<\/th>\n<th style=\"width: 29.288%;\" rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center; width: 11.165%;\">&gt;<\/th>\n<th style=\"text-align: center; width: 7.9288%;\">\u2264<\/th>\n<th style=\"text-align: center; width: 5.01618%;\">&gt;<\/th>\n<th style=\"text-align: center; width: 15.0485%;\">\u2264<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 11.165%;\">2,999<\/th>\n<th style=\"width: 7.9288%;\">3,5<\/th>\n<td style=\"width: 28.9644%;\">\u226414<\/td>\n<th style=\"width: 5.01618%;\">9<\/th>\n<th style=\"width: 15.0485%;\">11<\/th>\n<td style=\"width: 29.288%;\">\u226434<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 11.165%;\">3,5<\/th>\n<th style=\"width: 7.9288%;\">4,5<\/th>\n<td style=\"width: 28.9644%;\">\u226417<\/td>\n<th style=\"width: 5.01618%;\">11<\/th>\n<th style=\"width: 15.0485%;\">13<\/th>\n<td style=\"width: 29.288%;\">\u226444<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 11.165%;\">4,5<\/th>\n<th style=\"width: 7.9288%;\">6<\/th>\n<td style=\"width: 28.9644%;\">\u226419<\/td>\n<th style=\"width: 5.01618%;\">13<\/th>\n<th style=\"width: 15.0485%;\">17<\/th>\n<td style=\"width: 29.288%;\">\u226454<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 11.165%;\">6<\/th>\n<th style=\"width: 7.9288%;\">7<\/th>\n<td style=\"width: 28.9644%;\">\u226422<\/td>\n<th style=\"width: 5.01618%;\">17<\/th>\n<th style=\"width: 15.0485%;\">21<\/th>\n<td style=\"width: 29.288%;\">\u226464<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 11.165%;\">7<\/th>\n<th style=\"width: 7.9288%;\">9<\/th>\n<td style=\"width: 28.9644%;\">\u226424<\/td>\n<th style=\"width: 5.01618%;\">21<\/th>\n<th style=\"width: 15.0485%;\">Nessuna restrizione<\/th>\n<td style=\"width: 29.288%;\">\u226474<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84c1430 elementor-widget elementor-widget-text-editor\" data-id=\"84c1430\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n \t<li>Esempio 1: foro diritto \u00d812,9 mm in EN 1.0038 equiv.<\/li>\n \t<li>\u2192 utensile utilizzato: punta, profondit\u00e0 max: 200 mm<\/li>\n \t<li>Esempio 2: foro diritto \u00d813,1 mm in EN 1.0038 equiv.<\/li>\n \t<li>\u2192 utensile utilizzato: fresa, profondit\u00e0 max: 48 mm<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c721d8f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c721d8f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f139b3c\" data-id=\"f139b3c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e83613b elementor-widget elementor-widget-heading\" data-id=\"e83613b\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"box_2\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Intervalli di precisione quotabili automaticamente<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7778c0e elementor-widget elementor-widget-text-editor\" data-id=\"7778c0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tUn foro diritto pu\u00f2 essere trasformato in foro di precisione selezionando la voce \u201cTipo di tolleranza diametro foro\u201d. In questo modo \u00e8 possibile specificare tolleranze e profondit\u00e0 utile.\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86a0029 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86a0029\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a3d8601\" data-id=\"a3d8601\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c342e5 elementor-widget elementor-widget-heading\" data-id=\"0c342e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Lavorazione con fresa\n<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9216cb6 elementor-widget elementor-widget-text-editor\" data-id=\"9216cb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5b3d40 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"d5b3d40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover\">\n<tbody>\n<tr>\n<th colspan=\"2\" width=\"10%\">Diametro<\/th>\n<th colspan=\"3\" width=\"90%\">Intervalli di precisione<\/th>\n<\/tr>\n<tr>\n<th>&gt;<\/th>\n<th>\u2264<\/th>\n<th>Tolleranza di accoppiamento<\/th>\n<th>Tolleranza bidirezionale (valore minimo)\u200b<\/th>\n<th>Tolleranza unidirezionale (valore minimo)\u200b<\/th>\n<\/tr>\n<tr>\n<th>&#8211;<\/th>\n<th>3<\/th>\n<td class=\"elementCenter\" rowspan=\"22\">Grado IT7 o superiore<\/td>\n<td class=\"elementCenter\">0,005<\/td>\n<td class=\"elementCenter\">0,01<\/td>\n<\/tr>\n<tr>\n<th>3<\/th>\n<th>6<\/th>\n<td class=\"elementCenter\">0,006<\/td>\n<td class=\"elementCenter\">0,012<\/td>\n<\/tr>\n<tr>\n<th>6<\/th>\n<th>10<\/th>\n<td class=\"elementCenter\">0,008<\/td>\n<td class=\"elementCenter\">0,015<\/td>\n<\/tr>\n<tr>\n<th>10<\/th>\n<th>18<\/th>\n<td class=\"elementCenter\">0,009<\/td>\n<td class=\"elementCenter\">0,018<\/td>\n<\/tr>\n<tr>\n<th>18<\/th>\n<th>30<\/th>\n<td class=\"elementCenter\">0,011<\/td>\n<td class=\"elementCenter\">0,021<\/td>\n<\/tr>\n<tr>\n<th>30<\/th>\n<th>50<\/th>\n<td class=\"elementCenter\">0,013<\/td>\n<td class=\"elementCenter\">0,025<\/td>\n<\/tr>\n<tr>\n<th>50<\/th>\n<th>80<\/th>\n<td class=\"elementCenter\">0,015<\/td>\n<td class=\"elementCenter\">0,03<\/td>\n<\/tr>\n<tr>\n<th>80<\/th>\n<th>120<\/th>\n<td class=\"elementCenter\">0,018<\/td>\n<td class=\"elementCenter\">0,035<\/td>\n<\/tr>\n<tr>\n<th>120<\/th>\n<th>180<\/th>\n<td class=\"elementCenter\">0,02<\/td>\n<td class=\"elementCenter\">0,04<\/td>\n<\/tr>\n<tr>\n<th>180<\/th>\n<th>250<\/th>\n<td class=\"elementCenter\">0,023<\/td>\n<td class=\"elementCenter\">0,046<\/td>\n<\/tr>\n<tr>\n<th>250<\/th>\n<th>315<\/th>\n<td class=\"elementCenter\">0,026<\/td>\n<td class=\"elementCenter\">0,052<\/td>\n<\/tr>\n<tr>\n<th>315<\/th>\n<th>400<\/th>\n<td class=\"elementCenter\">0,029<\/td>\n<td class=\"elementCenter\">0,057<\/td>\n<\/tr>\n<tr>\n<th>400<\/th>\n<th>500<\/th>\n<td class=\"elementCenter\">0,032<\/td>\n<td class=\"elementCenter\">0,063<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d20f101 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d20f101\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fa9ee9d\" data-id=\"fa9ee9d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-534848f elementor-widget elementor-widget-heading\" data-id=\"534848f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Profondit\u00e0 effettive preventivabili automaticamente<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa800aa elementor-widget elementor-widget-text-editor\" data-id=\"fa800aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f213b25 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"f213b25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%; height: 192px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px;\" colspan=\"6\">Acciaio, Acciaio pre-temprato e acciaio per utensili<\/th>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"text-align: center; height: 24px;\" colspan=\"2\">Diametro<\/th>\n<th style=\"height: 48px;\" rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<th style=\"height: 24px;\" colspan=\"2\">Diametro<\/th>\n<th style=\"height: 48px;\" rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"text-align: center; height: 24px;\">&gt;<\/th>\n<th style=\"text-align: center; height: 24px;\">\u2264<\/th>\n<th style=\"text-align: center; height: 24px;\">&gt;<\/th>\n<th style=\"text-align: center; height: 24px;\">\u2264<\/th>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px;\">2,999<\/th>\n<th style=\"height: 24px;\">3,5<\/th>\n<td>\u226410<\/td>\n<th style=\"height: 24px;\">9<\/th>\n<th style=\"height: 24px;\">11<\/th>\n<td>\u226440<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px;\">3,5<\/th>\n<th style=\"height: 24px;\">4,5<\/th>\n<td>\u226412<\/td>\n<th style=\"height: 24px;\">11<\/th>\n<th style=\"height: 24px;\">13<\/th>\n<td>\u226450<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px;\">4,5<\/th>\n<th style=\"height: 24px;\">6<\/th>\n<td>\u226416<\/td>\n<th style=\"height: 24px;\">13<\/th>\n<th style=\"height: 24px;\">17<\/th>\n<td>\u226460<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px;\">6<\/th>\n<th style=\"height: 24px;\">7<\/th>\n<td>\u226420<\/td>\n<th style=\"height: 24px;\">17<\/th>\n<th style=\"height: 24px;\">21<\/th>\n<td>\u226480<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px;\">7<\/th>\n<th style=\"height: 24px;\">9<\/th>\n<td>\u226430<\/td>\n<th style=\"height: 24px;\">21<\/th>\n<th style=\"height: 24px;\">Nessuna restrizione<\/th>\n<td>\u2264100<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-980d70a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"980d70a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-be223a2\" data-id=\"be223a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be8a0c7 elementor-widget elementor-widget-text-editor\" data-id=\"be8a0c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1885187 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"1885187\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th colspan=\"6\">Alluminio<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center;\" colspan=\"2\">Diametro<\/th>\n<th rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<th style=\"ext-align: center;\" colspan=\"2\">Diametro<\/th>\n<th rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center;\">&gt;<\/th>\n<th style=\"text-align: center;\">\u2264<\/th>\n<th style=\"text-align: center;\">&gt;<\/th>\n<th style=\"text-align: center;\">\u2264<\/th>\n<\/tr>\n<tr>\n<th>2,999<\/th>\n<th>3,5<\/th>\n<td>\u226410<\/td>\n<th>9<\/th>\n<th>11<\/th>\n<td>\u226440<\/td>\n<\/tr>\n<tr>\n<th>3,5<\/th>\n<th>4,5<\/th>\n<td>\u226412<\/td>\n<th>11<\/th>\n<th>13<\/th>\n<td>\u226450<\/td>\n<\/tr>\n<tr>\n<th>4,5<\/th>\n<th>6<\/th>\n<td>\u226416<\/td>\n<th>13<\/th>\n<th>17<\/th>\n<td>\u226460<\/td>\n<\/tr>\n<tr>\n<th>6<\/th>\n<th>7<\/th>\n<td>\u226425<\/td>\n<th>17<\/th>\n<th>21<\/th>\n<td>\u226480<\/td>\n<\/tr>\n<tr>\n<th>7<\/th>\n<th>9<\/th>\n<td>\u226430<\/td>\n<th>21<\/th>\n<th>Nessuna restrizione<\/th>\n<td>\u2264100<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cab0425 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cab0425\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6e08d38\" data-id=\"6e08d38\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cae25d2 elementor-widget elementor-widget-text-editor\" data-id=\"cae25d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb4644b tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"fb4644b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%; height: 191px;\">\n<tbody>\n<tr style=\"height: 21px;\">\n<th style=\"width: 97.3378%; height: 21px;\" colspan=\"6\">Acciaio inossidabile<\/th>\n<\/tr>\n<tr style=\"height: 21px;\">\n<th style=\"text-align: center; width: 19.1348%; height: 21px;\" colspan=\"2\">Diametro<\/th>\n<th style=\"width: 28.9517%; height: 42px;\" rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<th style=\"width: 19.9667%; height: 21px;\" colspan=\"2\">Diametro<\/th>\n<th style=\"width: 29.2845%; height: 42px;\" rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<\/tr>\n<tr style=\"height: 21px;\">\n<th style=\"text-align: center; width: 11.1481%; height: 21px;\">&gt;<\/th>\n<th style=\"text-align: center; width: 7.98669%; height: 21px;\">\u2264<\/th>\n<th style=\"text-align: center; width: 4.82529%; height: 21px;\">&gt;<\/th>\n<th style=\"text-align: center; width: 15.1414%; height: 21px;\">\u2264<\/th>\n<\/tr>\n<tr style=\"height: 21px;\">\n<th style=\"width: 11.1481%; height: 21px;\">2,999<\/th>\n<th style=\"width: 7.98669%; height: 21px;\">3,5<\/th>\n<td>\u226410<\/td>\n<th style=\"width: 4.82529%; height: 21px;\">9<\/th>\n<th style=\"width: 15.1414%; height: 21px;\">11<\/th>\n<td>\u226432<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<th style=\"width: 11.1481%; height: 21px;\">3,5<\/th>\n<th style=\"width: 7.98669%; height: 21px;\">4,5<\/th>\n<td>\u226412<\/td>\n<th style=\"width: 4.82529%; height: 21px;\">11<\/th>\n<th style=\"width: 15.1414%; height: 21px;\">13<\/th>\n<td>\u226440<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<th style=\"width: 11.1481%; height: 21px;\">4,5<\/th>\n<th style=\"width: 7.98669%; height: 21px;\">6<\/th>\n<td>\u226416<\/td>\n<th style=\"width: 4.82529%; height: 21px;\">13<\/th>\n<th style=\"width: 15.1414%; height: 21px;\">17<\/th>\n<td>\u226448<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<th style=\"width: 11.1481%; height: 21px;\">6<\/th>\n<th style=\"width: 7.98669%; height: 21px;\">7<\/th>\n<td>\u226420<\/td>\n<th style=\"width: 4.82529%; height: 21px;\">17<\/th>\n<th style=\"width: 15.1414%; height: 21px;\">21<\/th>\n<td>\u226464<\/td>\n<\/tr>\n<tr style=\"height: 44px;\">\n<th style=\"width: 11.1481%; height: 44px;\">7<\/th>\n<th style=\"width: 7.98669%; height: 44px;\">9<\/th>\n<td>\u226424<\/td>\n<th style=\"width: 4.82529%; height: 44px;\">21<\/th>\n<th style=\"width: 15.1414%; height: 44px;\">Nessuna restrizione<\/th>\n<td>\u226480<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-db27128 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"db27128\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f25c6e8\" data-id=\"f25c6e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95ed65c elementor-widget elementor-widget-text-editor\" data-id=\"95ed65c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80e64d5 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"80e64d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th colspan=\"6\">Resina<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center;\" colspan=\"2\">Diametro<\/th>\n<th rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<th style=\"ext-align: center;\" colspan=\"2\">Diametro<\/th>\n<th rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center;\">&gt;<\/th>\n<th style=\"text-align: center;\">\u2264<\/th>\n<th style=\"text-align: center;\">&gt;<\/th>\n<th style=\"text-align: center;\">\u2264<\/th>\n<\/tr>\n<tr>\n<th>2,999<\/th>\n<th>3,5<\/th>\n<td>\u22645<\/td>\n<th>11<\/th>\n<th>13<\/th>\n<td>\u226420<\/td>\n<\/tr>\n<tr>\n<th>3,5<\/th>\n<th>4,5<\/th>\n<td>\u22646<\/td>\n<th>13<\/th>\n<th>18<\/th>\n<td>\u226424<\/td>\n<\/tr>\n<tr>\n<th>4,5<\/th>\n<th>7<\/th>\n<td>\u22648<\/td>\n<th>18<\/th>\n<th>21<\/th>\n<td>\u226436<\/td>\n<\/tr>\n<tr>\n<th>7<\/th>\n<th>10<\/th>\n<td>\u226412<\/td>\n<th>21<\/th>\n<th>Nessuna restrizione<\/th>\n<td>\u226440<\/td>\n<\/tr>\n<tr>\n<th>10<\/th>\n<th>11<\/th>\n<td>\u226416<\/td>\n<th colspan=\"3\">\u2013<\/th>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f043e36 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f043e36\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2bdc30b\" data-id=\"2bdc30b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ceea8d elementor-widget elementor-widget-text-editor\" data-id=\"7ceea8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07f1668 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"07f1668\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th style=\"width: 97.3378%;\" colspan=\"6\">\n<ul>\n \t<li>Piatti lucidati<\/li>\n \t<li>(EN 1.0038  equiv. (barra piatta), EN 1.1191  equiv. (barra piatta), EN 1.4301  equiv. (barra piatta), EN AW-6063  equiv. (barra piatta))<\/li>\n<\/ul>\n<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center; width: 20.7987%;\" colspan=\"2\">Diametro<\/th>\n<th style=\"width: 31.2812%;\" rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<th style=\"width: 13.9767%;\" colspan=\"2\">Diametro<\/th>\n<th style=\"width: 31.2812%;\" rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center; width: 12.1464%;\">&gt;<\/th>\n<th style=\"text-align: center; width: 8.65225%;\">\u2264<\/th>\n<th style=\"text-align: center; width: 5.32446%;\">&gt;<\/th>\n<th style=\"text-align: center; width: 8.65225%;\">\u2264<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 12.1464%;\">2,999<\/th>\n<th style=\"width: 8.65225%;\">3,5<\/th>\n<td style=\"width: 31.2812%;\">\u22667<\/td>\n<th style=\"width: 5.32446%;\">9<\/th>\n<th style=\"width: 8.65225%;\">11<\/th>\n<td style=\"width: 31.2812%;\">\u226631<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 12.1464%;\">3,5<\/th>\n<th style=\"width: 8.65225%;\">4,5<\/th>\n<td style=\"width: 31.2812%;\">\u226611<\/td>\n<th style=\"width: 5.32446%;\">11<\/th>\n<th style=\"width: 8.65225%;\">13<\/th>\n<td style=\"width: 31.2812%;\">\u226639<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 12.1464%;\">4,5<\/th>\n<th style=\"width: 8.65225%;\">6<\/th>\n<td style=\"width: 31.2812%;\">\u226615<\/td>\n<th style=\"width: 5.32446%;\">13<\/th>\n<th style=\"width: 8.65225%;\">17<\/th>\n<td style=\"width: 31.2812%;\">\u226647<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 12.1464%;\">6<\/th>\n<th style=\"width: 8.65225%;\">7<\/th>\n<td style=\"width: 31.2812%;\">\u226619<\/td>\n<th style=\"width: 5.32446%;\">17<\/th>\n<th style=\"width: 8.65225%;\">21<\/th>\n<td style=\"width: 31.2812%;\">\u226663<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 12.1464%;\">7<\/th>\n<th style=\"width: 8.65225%;\">9<\/th>\n<td style=\"width: 31.2812%;\">\u226623<\/td>\n<th style=\"width: 5.32446%;\">21<\/th>\n<th style=\"width: 8.65225%;\">Nessuna restrizione<\/th>\n<td style=\"width: 31.2812%;\">\u226673<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-43cfaf8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"43cfaf8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c3bb09\" data-id=\"6c3bb09\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f27ed7a elementor-widget elementor-widget-text-editor\" data-id=\"f27ed7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLe profondit\u00e0 effettive preventivabili automaticamente sono diverse a causa della lavorazione dell&#8217;alesatore quando la tolleranza di montaggio \u00e8 H7 per i seguenti diametri.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-426ab41 elementor-widget elementor-widget-text-editor\" data-id=\"426ab41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52d64af tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"52d64af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"print_block\">\n<div class=\"tableStickyHead\">\n<table class=\"tableHover\">\n<thead>\n<tr>\n<th style=\"width: 30%;\" rowspan=\"2\">Diametri con alesatore<\/th>\n<th style=\"width: 70%;\" colspan=\"7\">Profondit\u00e0 Efficace (Approssimativa)<\/th>\n<\/tr>\n<tr>\n<th>\n<ul>\n \t<li>EN 1.0038 equiv.<\/li>\n \t<li>EN 1.1191 equiv.<\/li>\n \t<li>EN 1.1206 equiv.<\/li>\n<\/ul>\n<\/th>\n<th>Acciaio pre-temprato e acciaio per utensili<\/th>\n<th>EN 1.0038 equiv. (materiale ricotto)<\/th>\n<th>Acciaio inossidabile<\/th>\n<th>Alluminio<\/th>\n<th>Resina<\/th>\n<th>\n<ul>\n \t<li>Piatti lucidati<\/li>\n \t<li>(EN 1.0038  equiv. (barra piatta), EN 1.1191  equiv. (barra piatta), EN 1.4301  equiv. (barra piatta), EN AW-6063  equiv. (barra piatta))<\/li>\n<\/ul>\n<\/th>\n<\/tr>\n<\/thead>\n<\/table>\n<\/div>\n<table class=\"tableHover mT0\">\n<tbody>\n<tr>\n<th style=\"width: 30%;\">2<\/th>\n<td style=\"width: 10%;\" rowspan=\"9\">\u2264 Diametro * 10<\/td>\n<td style=\"width: 10%;\">\u2264 Diametro * 9<\/td>\n<td style=\"width: 10%;\">\u2264 Diametro * 6<\/td>\n<td style=\"width: 10%;\">\u2264 Diametro * 9<\/td>\n<td style=\"width: 10%;\" rowspan=\"11\">\u2264 Diametro * 10<\/td>\n<td style=\"width: 10%;\">\u2264 Diametro * 12<\/td>\n<td style=\"width: 10%;\">\u2264 Diametro * 6<\/td>\n<\/tr>\n<tr>\n<th>3<\/th>\n<td>\u2264 Diametro * 9<\/td>\n<td>\u2264 Diametro * 8<\/td>\n<td>\u2264 Diametro * 9<\/td>\n<td>\u2264 Diametro * 12<\/td>\n<td>\u2264 Diametro * 8<\/td>\n<\/tr>\n<tr>\n<th>4<\/th>\n<td rowspan=\"7\">\u2264 Diametro * 10<\/td>\n<td rowspan=\"7\">\u2264 Diametro * 10<\/td>\n<td>\u2264 Diametro * 8<\/td>\n<td>\u2264 Diametro * 10<\/td>\n<td rowspan=\"7\">\u2264 Diametro * 10<\/td>\n<\/tr>\n<tr>\n<th>5<\/th>\n<td rowspan=\"4\">\u2264 Diametro * 10<\/td>\n<td>\u2264 Diametro * 15<\/td>\n<\/tr>\n<tr>\n<th>6<\/th>\n<td>\u2264 Diametro * 8<\/td>\n<\/tr>\n<tr>\n<th>7<\/th>\n<td>\u2264 Diametro * 6<\/td>\n<\/tr>\n<tr>\n<th>8\/9<\/th>\n<td>\u2264 Diametro * 5<\/td>\n<\/tr>\n<tr>\n<th>10\/11<\/th>\n<td rowspan=\"4\">\u2264100<\/td>\n<td>\u2264 Diametro * 5<\/td>\n<\/tr>\n<tr>\n<th>12\/13<\/th>\n<td rowspan=\"3\"><\/td>\n<\/tr>\n<tr>\n<th>14\/15\/16<\/th>\n<td>\u2264 Diametro * 9<\/td>\n<td>\u2264 Diametro * 9<\/td>\n<td>\u2264 Diametro * 9<\/td>\n<td>\u2264 Diametro * 9<\/td>\n<\/tr>\n<tr>\n<th>17\/18\/19\/20<\/th>\n<td>\u2264 Diametro * 8<\/td>\n<td>\u2264 Diametro * 8<\/td>\n<td>\u2264 Diametro * 8<\/td>\n<td>\u2264 Diametro * 8<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-31109c2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"31109c2\" data-element_type=\"section\" data-e-type=\"section\" id=\"box_3\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a4615f0\" data-id=\"a4615f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c31571 elementor-widget elementor-widget-heading\" data-id=\"1c31571\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"box_3\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fori filettati<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1673829 elementor-widget elementor-widget-text-editor\" data-id=\"1673829\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLe dimensioni di filettatura disponibili e le profondit\u00e0 efficaci specificabili per il servizio di taglio sono le seguenti.\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4047c4 elementor-widget elementor-widget-text-editor\" data-id=\"e4047c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tSe la scanalatura del maschio \u00e8 poco profonda, potrebbe non essere possibile ottenere almeno due filetti a causa della forma della testa e del taglio della punta dell&#8217;utensile.\nPer garantire una forza di serraggio adeguata, si consiglia di prevedere almeno 3 filetti.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a9a2cd8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a9a2cd8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d98614e\" data-id=\"d98614e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06926ae elementor-widget elementor-widget-heading\" data-id=\"06926ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Profondit\u00e0 efficaci di filettatura preventivabili automaticamente\n<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-936693d elementor-widget elementor-widget-text-editor\" data-id=\"936693d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9fbf83 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"c9fbf83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"print_block\">\n<div class=\"tableStickyHead\">\n<table class=\"mT0 tableHover\" style=\"overflow-wrap: break-word;\">\n<thead>\n<tr>\n<th style=\"width: 9%; padding: 0; border: none;\"><\/th>\n<th style=\"width: 9%; padding: 0; border: none;\"><\/th>\n<th style=\"width: 9%; padding: 0; border: none;\"><\/th>\n<th style=\"width: 10%; padding: 0; border: none;\"><\/th>\n<th style=\"width: 17%; ; padding: 0; border: none;\"><\/th>\n<th style=\"width: 7%; padding: 0; border: none;\"><\/th>\n<th style=\"width: 7%; padding: 0; border: none;\"><\/th>\n<th style=\"width: 16%; padding: 0; border: none;\"><\/th>\n<th style=\"width: 16%; ; padding: 0; border: none;\"><\/th>\n<\/tr>\n<tr>\n<th style=\"width: 9%;\" rowspan=\"2\">Diametro della Filettatura<\/th>\n<th style=\"width: 9%;\" rowspan=\"2\">Passo<\/th>\n<th style=\"width: 9%;\" rowspan=\"2\">Filettatura Grossa<\/th>\n<th style=\"width: 10%;\" rowspan=\"2\">Filettatura Fine<\/th>\n<th colspan=\"5\">Profondit\u00e0 Efficace (Approssimativa)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 17%;\">Acciaio (eccetto EN 1.0038 equiv. (materiale ricotto)),\nAlluminio, Acciaio inossidabile<\/th>\n<th style=\"width: 7%;\">EN 1.0038 equiv. (materiale ricotto)<\/th>\n<th style=\"width: 7%;\">Acciaio pre-temprato e acciaio per utensili<\/th>\n<th style=\"width: 16%;\">resina<\/th>\n<th style=\"width: 16%;\">\n<ul>\n \t<li>Piatti lucidati<\/li>\n \t<li>(EN 1.0038  equiv. (barra piatta), EN 1.1191  equiv. (barra piatta), EN 1.4301  equiv. (barra piatta), EN AW-6063  equiv. (barra piatta))<\/li>\n<\/ul>\n<\/th>\n<\/tr>\n<\/thead>\n<\/table>\n<\/div>\n<table class=\"tableHover mT0\" style=\"overflow-wrap: break-word;\">\n<tbody>\n<tr>\n<td style=\"width: 9%;\" rowspan=\"2\">M2<\/td>\n<td style=\"width: 9%;\">0,25<\/td>\n<td style=\"width: 9%;\"><\/td>\n<td style=\"width: 10%;\">\u2713<\/td>\n<td style=\"width: 17%;\" rowspan=\"30\">\u2264 Diametro della Filettatura * 5<\/td>\n<td style=\"width: 7%;\" rowspan=\"2\">\u2264 Diametro della Filettatura * 3<\/td>\n<td style=\"width: 7%;\" rowspan=\"4\">\u2264 Diametro della Filettatura * 4<\/td>\n<td style=\"width: 16%;\" rowspan=\"2\">\u2264 Diametro della Filettatura * 6<\/td>\n<td style=\"width: 16%;\" rowspan=\"4\">\u2264 Diametro della Filettatura * 2<\/td>\n<\/tr>\n<tr>\n<td>0,4<\/td>\n<td>\u2713<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td rowspan=\"2\">M2,5<\/td>\n<td>0,35<\/td>\n<td><\/td>\n<td>\u2713<\/td>\n<td rowspan=\"2\">\u2264 Diametro della Filettatura * 3<\/td>\n<td rowspan=\"2\">\u2264 Diametro della Filettatura * 5<\/td>\n<\/tr>\n<tr>\n<td>0,45<\/td>\n<td>\u2713<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td rowspan=\"2\">M3<\/td>\n<td>0,35<\/td>\n<td><\/td>\n<td>\u2713<\/td>\n<td rowspan=\"2\">\u2264 Diametro della Filettatura * 4<\/td>\n<td rowspan=\"26\">\u2264 Diametro della Filettatura * 5<\/td>\n<td>\u2264 Diametro della Filettatura * 4<\/td>\n<td rowspan=\"26\">\u2264 Diametro della Filettatura * 3<\/td>\n<\/tr>\n<tr>\n<td>0,5<\/td>\n<td>\u2713<\/td>\n<td><\/td>\n<td>\u2264 Diametro della Filettatura * 5<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"2\">M4<\/td>\n<td>0,5<\/td>\n<td><\/td>\n<td>\u2713<\/td>\n<td rowspan=\"24\">\u2264 Diametro della Filettatura * 5<\/td>\n<td>\u2264 Diametro della Filettatura * 4<\/td>\n<\/tr>\n<tr>\n<td>0,7<\/td>\n<td>\u2713<\/td>\n<td><\/td>\n<td>\u2264 Diametro della Filettatura * 5<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"2\">M5<\/td>\n<td>0,5<\/td>\n<td><\/td>\n<td>\u2713<\/td>\n<td>\u2264 Diametro della Filettatura * 4<\/td>\n<\/tr>\n<tr>\n<td>0,8<\/td>\n<td>\u2713<\/td>\n<td><\/td>\n<td>\u2264 Diametro della Filettatura * 5<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"2\">M6<\/td>\n<td>0,75<\/td>\n<td><\/td>\n<td>\u2713<\/td>\n<td>\u2264 Diametro della Filettatura * 4<\/td>\n<\/tr>\n<tr>\n<td>1<\/td>\n<td>\u2713<\/td>\n<td><\/td>\n<td>\u2264 Diametro della Filettatura * 5<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"3\">M8<\/td>\n<td>0,75<\/td>\n<td><\/td>\n<td>\u2713<\/td>\n<td rowspan=\"2\">\u2264 Diametro della Filettatura * 4<\/td>\n<\/tr>\n<tr>\n<td>1<\/td>\n<td><\/td>\n<td>\u2713<\/td>\n<\/tr>\n<tr>\n<td>1,25<\/td>\n<td>\u2713<\/td>\n<td><\/td>\n<td>\u2264 Diametro della Filettatura * 5<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"4\">M10<\/td>\n<td>0,75<\/td>\n<td><\/td>\n<td>\u2713<\/td>\n<td rowspan=\"3\">\u2264 Diametro della Filettatura * 4<\/td>\n<\/tr>\n<tr>\n<td>1<\/td>\n<td><\/td>\n<td>\u2713<\/td>\n<\/tr>\n<tr>\n<td>1,25<\/td>\n<td><\/td>\n<td>\u2713<\/td>\n<\/tr>\n<tr>\n<td>1,5<\/td>\n<td>\u2713<\/td>\n<td><\/td>\n<td>\u2264 Diametro della Filettatura * 5<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"4\">M12<\/td>\n<td>1<\/td>\n<td><\/td>\n<td>\u2713<\/td>\n<td rowspan=\"3\">\u2264 Diametro della Filettatura * 4<\/td>\n<\/tr>\n<tr>\n<td>1,25<\/td>\n<td><\/td>\n<td>\u2713<\/td>\n<\/tr>\n<tr>\n<td>1,5<\/td>\n<td><\/td>\n<td>\u2713<\/td>\n<\/tr>\n<tr>\n<td>1,75<\/td>\n<td>\u2713<\/td>\n<td><\/td>\n<td>\u2264 Diametro della Filettatura * 4<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"4\">M14<\/td>\n<td>1<\/td>\n<td><\/td>\n<td>\u2713<\/td>\n<td rowspan=\"3\">\u2264 Diametro della Filettatura * 3<\/td>\n<\/tr>\n<tr>\n<td>1,25<\/td>\n<td><\/td>\n<td>\u2713<\/td>\n<\/tr>\n<tr>\n<td>1,5<\/td>\n<td><\/td>\n<td>\u2713<\/td>\n<\/tr>\n<tr>\n<td>2<\/td>\n<td>\u2713<\/td>\n<td><\/td>\n<td>\u2264 Diametro della Filettatura * 2<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"3\">M16<\/td>\n<td>1<\/td>\n<td><\/td>\n<td>\u2713<\/td>\n<td rowspan=\"3\">\u2264 Diametro della Filettatura * 3<\/td>\n<\/tr>\n<tr>\n<td>1,5<\/td>\n<td><\/td>\n<td>\u2713<\/td>\n<\/tr>\n<tr>\n<td>2<\/td>\n<td>\u2713<\/td>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c992a0 elementor-widget elementor-widget-heading\" data-id=\"3c992a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Profondit\u00e0 effettiva dei maschi quotabili<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c2ef9c elementor-widget elementor-widget-text-editor\" data-id=\"3c2ef9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9fb5671 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"9fb5671\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"print_block\">\n<div class=\"tableStickyHead\">\n<table class=\"mT0 tableHover\" style=\"overflow-wrap: break-word;\">\n<thead>\n<tr>\n<th style=\"width: 10%; padding: 0; border: none;\"><\/th>\n<th style=\"width: 10%; padding: 0; border: none;\"><\/th>\n<th style=\"width: 10%; padding: 0; border: none;\"><\/th>\n<th style=\"width: 16%; padding: 0; border: none;\"><\/th>\n<th style=\"width: 12%; padding: 0; border: none;\"><\/th>\n<th style=\"padding: 0; border: none;\"><\/th>\n<th style=\"width: 15%; padding: 0; border: none;\"><\/th>\n<th style=\"width: 15%; padding: 0; border: none;\"><\/th>\n<\/tr>\n<tr>\n<th style=\"width: 10%;\" rowspan=\"2\">Diametro della Filettatura<\/th>\n<th style=\"width: 10%;\" rowspan=\"2\">Filettatura Grossa<\/th>\n<th style=\"width: 10%;\" rowspan=\"2\">Filettatura Fine<\/th>\n<th colspan=\"5\">Profondit\u00e0 Efficace (Approssimativa)<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 16%;\">Acciaio (eccetto EN 1.0038 equiv. (materiale ricotto)),\nAlluminio, Acciaio (inossidabile)<\/th>\n<th style=\"width: 12%;\">EN 1.0038 equiv. (materiale ricotto)<\/th>\n<th>Acciaio pre-temprato e acciaio per utensili<\/th>\n<th style=\"width: 15%;\">Effective Depth (Approximate) (Resina)<\/th>\n<th style=\"width: 15%;\">\n<ul>\n \t<li>Piatti lucidati<\/li>\n \t<li>(EN 1.0038  equiv. (barra piatta), EN 1.1191  equiv. (barra piatta), EN 1.4301  equiv. (barra piatta), EN AW-6063  equiv. (barra piatta))<\/li>\n<\/ul>\n<\/th>\n<\/tr>\n<\/thead>\n<\/table>\n<\/div>\n<table class=\"tableHover mT0\" style=\"overflow-wrap: break-word;\">\n<tbody>\n<tr>\n<th style=\"width: 10%;\">No.4-40<\/th>\n<td class=\"\" style=\"width: 10%;\">\u2713<\/td>\n<td class=\"\" style=\"width: 10%;\"><\/td>\n<td class=\"\" style=\"width: 16%;\" rowspan=\"12\">\u2264 Diametro della Filettatura\n* 3<\/td>\n<td class=\"\" style=\"width: 12%;\" rowspan=\"12\">\uff0d<\/td>\n<td rowspan=\"12\">\uff0d<\/td>\n<td class=\"\" style=\"width: 15%;\" rowspan=\"12\">\uff0d<\/td>\n<td style=\"width: 15%;\" rowspan=\"12\">\uff0d<\/td>\n<\/tr>\n<tr>\n<th>No.6-32<\/th>\n<td>\u2713<\/td>\n<td class=\"\"><\/td>\n<\/tr>\n<tr>\n<th>No.8-32<\/th>\n<td>\u2713<\/td>\n<td class=\"\"><\/td>\n<\/tr>\n<tr>\n<th>No.10-24<\/th>\n<td>\u2713<\/td>\n<td class=\"\"><\/td>\n<\/tr>\n<tr>\n<th>No.10-32<\/th>\n<td><\/td>\n<td class=\"\">\u2713<\/td>\n<\/tr>\n<tr>\n<th>1\/4-20<\/th>\n<td>\u2713<\/td>\n<td class=\"\"><\/td>\n<\/tr>\n<tr>\n<th>1\/4-28<\/th>\n<td><\/td>\n<td class=\"\">\u2713<\/td>\n<\/tr>\n<tr>\n<th>5\/16-18<\/th>\n<td>\u2713<\/td>\n<td class=\"\"><\/td>\n<\/tr>\n<tr>\n<th>3\/8-16<\/th>\n<td><\/td>\n<td class=\"\">\u2713<\/td>\n<\/tr>\n<tr>\n<th>3\/8-24<\/th>\n<td>\u2713<\/td>\n<td class=\"\"><\/td>\n<\/tr>\n<tr>\n<th>1\/2-13<\/th>\n<td>\u2713<\/td>\n<td class=\"\"><\/td>\n<\/tr>\n<tr>\n<th>5\/8-11<\/th>\n<td class=\"\">\u2713<\/td>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c170d13 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c170d13\" data-element_type=\"section\" data-e-type=\"section\" id=\"box_4\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-503561d\" data-id=\"503561d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-094dfb3 elementor-widget elementor-widget-heading\" data-id=\"094dfb3\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"box_4\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fori con inserto\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91a85f4 elementor-widget elementor-widget-text-editor\" data-id=\"91a85f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le dimensioni disponibili degli inserti e le profondit\u00e0 effettive specificabili per il servizio di taglio sono le seguenti.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f8aac79 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f8aac79\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-65ebf8c\" data-id=\"65ebf8c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2296ed elementor-widget elementor-widget-heading\" data-id=\"f2296ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Dimensioni preventivabili<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c27b5b elementor-widget elementor-widget-text-editor\" data-id=\"4c27b5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31b0f14 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"31b0f14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th>Diametro della Filettatura<\/th>\n<th>Passo<\/th>\n<th>Filettatura Grossa<\/th>\n<th>Lunghezza nominale (Alluminio e resina)<\/th>\n<th style=\"width: 20%;\">\n<ul>\n \t<li>Piatti lucidati<\/li>\n \t<li>(EN 1.0038 equiv. (barra piatta), EN 1.1191 equiv. (barra piatta), EN 1.4301 equiv. (barra piatta), EN AW-6063 equiv. (barra piatta))<\/li>\n<\/ul>\n<\/th>\n<\/tr>\n<tr>\n<td>M2<\/td>\n<td>0,4<\/td>\n<td>\u2713<\/td>\n<td>0,5D, 1D, 1,5D, 2D<\/td>\n<td>1D,1,5D,2D<\/td>\n<\/tr>\n<tr>\n<td>M2,5<\/td>\n<td>0,45<\/td>\n<td>\u2713<\/td>\n<td>0,5D, 1D, 1,5D, 2D<\/td>\n<td style=\"width: 20%;\">1D,1,5D,2D<\/td>\n<\/tr>\n<tr>\n<td>M3<\/td>\n<td>0,5<\/td>\n<td>\u2713<\/td>\n<td>0,5D, 1D, 1,5D, 2D<\/td>\n<td style=\"width: 20%;\">1D,1,5D,2D<\/td>\n<\/tr>\n<tr>\n<td>M4<\/td>\n<td>0,7<\/td>\n<td>\u2713<\/td>\n<td>0,5D, 1D, 1,5D, 2D<\/td>\n<td style=\"width: 20%;\">1D,1,5D,2D<\/td>\n<\/tr>\n<tr>\n<td>M5<\/td>\n<td>0,8<\/td>\n<td>\u2713<\/td>\n<td>0,5D, 1D, 1,5D, 2D<\/td>\n<td style=\"width: 20%;\">1D,1,5D,2D<\/td>\n<\/tr>\n<tr>\n<td>M6<\/td>\n<td>1<\/td>\n<td>\u2713<\/td>\n<td>0,5D, 1D, 1,5D, 2D<\/td>\n<td style=\"width: 20%;\">1D,1,5D,2D<\/td>\n<\/tr>\n<tr>\n<td>M8<\/td>\n<td>1,25<\/td>\n<td>\u2713<\/td>\n<td>0,5D, 1D, 1,5D, 2D<\/td>\n<td style=\"width: 20%;\">1D,1,5D,2D<\/td>\n<\/tr>\n<tr>\n<td>M10<\/td>\n<td>1,5<\/td>\n<td>\u2713<\/td>\n<td>0,5D, 1D, 1,5D, 2D<\/td>\n<td style=\"width: 20%;\">1D,1,5D,2D<\/td>\n<\/tr>\n<tr>\n<td>M12<\/td>\n<td>1,75<\/td>\n<td>\u2713<\/td>\n<td>0,5D, 1D, 1,5D, 2D<\/td>\n<td style=\"width: 20%;\">1D,1,5D,2D<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-790cfe4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"790cfe4\" data-element_type=\"section\" data-e-type=\"section\" id=\"box_5\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-27e6357\" data-id=\"27e6357\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ddccf90 elementor-widget elementor-widget-heading\" data-id=\"ddccf90\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"box_5\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fori a 1 scalino<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0e8914d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0e8914d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-61c8769\" data-id=\"61c8769\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6b4e55 elementor-widget elementor-widget-image\" data-id=\"f6b4e55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"167\" height=\"152\" src=\"https:\/\/de.meviy.misumi-ec.com\/help\/wp-content\/uploads\/2021\/02\/39856_01_deIT.png\" class=\"attachment-large size-large wp-image-56156\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-75f1083\" data-id=\"75f1083\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85baae5 elementor-widget elementor-widget-text-editor\" data-id=\"85baae5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nei fori a 1 scalino, il livello superiore e quello inferiore possono essere combinazioni diverse di tipo foro e tolleranza di diametro.<\/p><p>Le specifiche di precisione e gli standard per i fori filettati e di precisione sono descritti sopra.<\/p><p>I fori con inserto possono essere selezionati ovunque sia selezionabile un foro filettato (solo per alluminio e resina).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-144dbeb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"144dbeb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-85133ae\" data-id=\"85133ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62ea41e tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"62ea41e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th width=\"10%\">Passo superiore<\/th>\n<td>Foro diritto<\/td>\n<td>Foro diritto<\/td>\n<td>Foro diritto<\/td>\n<td>Foro di precisione<\/td>\n<td>Foro di precisione<\/td>\n<td>Foro di precisione<\/td>\n<td>Foro filettato<\/td>\n<td>Foro filettato<\/td>\n<\/tr>\n<tr>\n<th>Grado inferiore<\/th>\n<td>Foro diritto<\/td>\n<td>Foro di precisione<\/td>\n<td>Foro filettato<\/td>\n<td>Foro diritto<\/td>\n<td>Foro di precisione<\/td>\n<td>Foro filettato<\/td>\n<td>Foro diritto<\/td>\n<td>Foro pilota filettato<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44f2a3d elementor-widget elementor-widget-text-editor\" data-id=\"44f2a3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t*Quando il livello superiore \u00e8 un foro filettato, pu\u00f2 formarsi un profilo conico nella zona di transizione tra i due livelli durante la lavorazione del foro guida.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c38852 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c38852\" data-element_type=\"section\" data-e-type=\"section\" id=\"box_6\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ffe6824\" data-id=\"ffe6824\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f4268a4 elementor-widget elementor-widget-heading\" data-id=\"f4268a4\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"box_6\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fori a 2 scalini\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-618356b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"618356b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b6fe4f8\" data-id=\"b6fe4f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a67e55c elementor-widget elementor-widget-image\" data-id=\"a67e55c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"153\" height=\"152\" src=\"https:\/\/de.meviy.misumi-ec.com\/help\/wp-content\/uploads\/2021\/02\/39856_02_deIT.png\" class=\"attachment-large size-large wp-image-56162\" alt=\"\" srcset=\"https:\/\/de.meviy.misumi-ec.com\/help\/wp-content\/uploads\/2021\/02\/39856_02_deIT.png 153w, https:\/\/de.meviy.misumi-ec.com\/help\/wp-content\/uploads\/2021\/02\/39856_02_deIT-150x150.png 150w, https:\/\/de.meviy.misumi-ec.com\/help\/wp-content\/uploads\/2021\/02\/39856_02_deIT-100x100.png 100w\" sizes=\"(max-width: 153px) 100vw, 153px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ef082c7\" data-id=\"ef082c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bee06b5 elementor-widget elementor-widget-text-editor\" data-id=\"bee06b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nei fori a 2 scalini, i livelli superiore, intermedio e inferiore possono essere combinazioni diverse di tipi di foro e di tolleranze di diametro.<\/p><p>Le specifiche di precisione e gli standard per i fori filettati e di precisione sono descritti sopra.<\/p><p>*I fori con inserto possono essere selezionati ovunque sia selezionabile un foro filettato (solo per alluminio e resina).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bbdf068 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bbdf068\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-90861ed\" data-id=\"90861ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55576ef tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"55576ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th width=\"10%\">Grado superiore<\/th>\n<td>Foro dritto<\/td>\n<td>Foro dritto<\/td>\n<td>Foro dritto<\/td>\n<td>Foro dritto<\/td>\n<td>Foro dritto<\/td>\n<td>Foro dritto<\/td>\n<td>Foro dritto<\/td>\n<\/tr>\n<tr>\n<th>Grado intermedio<\/th>\n<td>Foro dritto<\/td>\n<td>Foro dritto<\/td>\n<td>Foro dritto<\/td>\n<td>Foro di precisione<\/td>\n<td>Foro di precisione<\/td>\n<td>Foro di precisione<\/td>\n<td>Foro di precisione<\/td>\n<\/tr>\n<tr>\n<th>Grado inferiore<\/th>\n<td>Foro dritto<\/td>\n<td>Foro di precisione<\/td>\n<td>Foro di precisione<\/td>\n<td>Foro di precisione<\/td>\n<td>Foro dritto<\/td>\n<td>Foro di precisione<\/td>\n<td>Foro dritto<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8074e6b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8074e6b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ae92d34\" data-id=\"ae92d34\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38b8842 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"38b8842\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th width=\"10%\">Grado superiore<\/th>\n<td>Foro dritto<\/td>\n<td>Foro filettato<\/td>\n<td>Foro filettato<\/td>\n<td>Foro filettato<\/td>\n<td>Foro filettato<\/td>\n<td>Foro filettato<\/td>\n<td>Foro filettato<\/td>\n<td>Fori di precisione<\/td>\n<\/tr>\n<tr>\n<th>Grado intermedio<\/th>\n<td>Foro pilota filettato<\/td>\n<td>Foro dritto<\/td>\n<td>Foro dritto<\/td>\n<td>Foro dritto<\/td>\n<td>Foro pilota filettato<\/td>\n<td>Foro pilota filettato<\/td>\n<td>Foro pilota filettato<\/td>\n<td>Foro dritto<\/td>\n<\/tr>\n<tr>\n<th>Grado inferiore<\/th>\n<td>Foro filettato<\/td>\n<td>Foro dritto<\/td>\n<td>Fori di precisione<\/td>\n<td>Foro filettato<\/td>\n<td>Foro dritto<\/td>\n<td>Fori di precisione<\/td>\n<td>Foro filettato<\/td>\n<td>Foro dritto<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0899d4d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0899d4d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6223b06\" data-id=\"6223b06\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a1c6779 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"a1c6779\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th width=\"10%\">Grado superiore<\/th>\n<td>Fori di precisione<\/td>\n<td>Fori di precisione<\/td>\n<td>Fori di precisione<\/td>\n<td>Fori di precisione<\/td>\n<td>Fori di precisione<\/td>\n<td>Fori di precisione<\/td>\n<td>Fori di precisione<\/td>\n<\/tr>\n<tr>\n<th>Grado intermedio<\/th>\n<td>Foro dritto<\/td>\n<td>Foro dritto<\/td>\n<td>Fori di precisione<\/td>\n<td>Fori di precisione<\/td>\n<td>Foro filettato<\/td>\n<td>Foro filettato<\/td>\n<td>Foro pilota filettato<\/td>\n<\/tr>\n<tr>\n<th>Grado inferiore<\/th>\n<td>Fori di precisione<\/td>\n<td>Foro filettato<\/td>\n<td>Fori di precisione<\/td>\n<td>Foro dritto<\/td>\n<td>Fori di precisione<\/td>\n<td>Foro dritto<\/td>\n<td>Foro filettato<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcfb90c elementor-widget elementor-widget-text-editor\" data-id=\"bcfb90c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>*Quando il grado superiore o inferiore \u00e8 un foro filettato, durante la lavorazione del foro pilota potrebbe formarsi una forma conica sul bordo tra il foro pilota e il grado intermedio.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d440e4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d440e4\" data-element_type=\"section\" data-e-type=\"section\" id=\"box_7\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b73f61\" data-id=\"5b73f61\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-789b021 elementor-widget elementor-widget-heading\" data-id=\"789b021\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"box_7\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fori svasati<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-305e806 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"305e806\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-69b47f3\" data-id=\"69b47f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3582f51 elementor-widget elementor-widget-image\" data-id=\"3582f51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"331\" height=\"196\" src=\"https:\/\/de.meviy.misumi-ec.com\/help\/wp-content\/uploads\/2021\/02\/39856_03_deIT.png\" class=\"attachment-full size-full wp-image-56168\" alt=\"\" srcset=\"https:\/\/de.meviy.misumi-ec.com\/help\/wp-content\/uploads\/2021\/02\/39856_03_deIT.png 331w, https:\/\/de.meviy.misumi-ec.com\/help\/wp-content\/uploads\/2021\/02\/39856_03_deIT-300x178.png 300w\" sizes=\"(max-width: 331px) 100vw, 331px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-17a7f69\" data-id=\"17a7f69\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-05b1bf3 elementor-widget elementor-widget-text-editor\" data-id=\"05b1bf3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I fori svasati sono lavorati secondo il modello.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-313f933 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"313f933\" data-element_type=\"section\" data-e-type=\"section\" id=\"box_8\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4d3d130\" data-id=\"4d3d130\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34cc6a9 elementor-widget elementor-widget-heading\" data-id=\"34cc6a9\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"box_8\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fori asolati<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd565cc elementor-widget elementor-widget-text-editor\" data-id=\"cd565cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La profondit\u00e0 di lavorazione auto-quotabile varia a seconda della larghezza.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-21b4824 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"21b4824\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5435a35\" data-id=\"5435a35\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c19f49 elementor-widget elementor-widget-heading\" data-id=\"3c19f49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Profondit\u00e0 effettive preventivabili automaticamente<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9dce56 elementor-widget elementor-widget-text-editor\" data-id=\"d9dce56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5946e08 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"5946e08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%; height: 192px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px;\" colspan=\"6\">Acciaio, Acciaio pre-temprato e acciaio per utensili<\/th>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"text-align: center; height: 24px;\" colspan=\"2\">Larghezza<\/th>\n<th style=\"height: 48px;\" rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<th style=\"height: 24px;\" colspan=\"2\">Larghezza<\/th>\n<th style=\"height: 48px;\" rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"text-align: center; height: 24px;\">&gt;<\/th>\n<th style=\"text-align: center; height: 24px;\">\u2264<\/th>\n<th style=\"text-align: center; height: 24px;\">&gt;<\/th>\n<th style=\"text-align: center; height: 24px;\">\u2264<\/th>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px;\">2,5<\/th>\n<th style=\"height: 24px;\">3<\/th>\n<td>\u226410<\/td>\n<th style=\"height: 24px;\">8<\/th>\n<th style=\"height: 24px;\">10<\/th>\n<td>\u226440<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px;\">3<\/th>\n<th style=\"height: 24px;\">4<\/th>\n<td>\u226412<\/td>\n<th style=\"height: 24px;\">10<\/th>\n<th style=\"height: 24px;\">12<\/th>\n<td>\u226450<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px;\">4<\/th>\n<th style=\"height: 24px;\">5<\/th>\n<td>\u226416<\/td>\n<th style=\"height: 24px;\">12<\/th>\n<th style=\"height: 24px;\">16<\/th>\n<td>\u226460<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px;\">5<\/th>\n<th style=\"height: 24px;\">6<\/th>\n<td>\u226420<\/td>\n<th style=\"height: 24px;\">16<\/th>\n<th style=\"height: 24px;\">20<\/th>\n<td>\u226480<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px;\">6<\/th>\n<th style=\"height: 24px;\">8<\/th>\n<td>\u226430<\/td>\n<th style=\"height: 24px;\">20<\/th>\n<th style=\"height: 24px;\">Nessuna restrizione<\/th>\n<td>\u2264100<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc9481a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc9481a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-23e9483\" data-id=\"23e9483\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-821bc0d elementor-widget elementor-widget-text-editor\" data-id=\"821bc0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e649787 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"e649787\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th colspan=\"6\">Alluminio<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center;\" colspan=\"2\">Larghezza<\/th>\n<th rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<th style=\"ext-align: center;\" colspan=\"2\">Larghezza<\/th>\n<th rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center;\">&gt;<\/th>\n<th style=\"text-align: center;\">\u2264<\/th>\n<th style=\"text-align: center;\">&gt;<\/th>\n<th style=\"text-align: center;\">\u2264<\/th>\n<\/tr>\n<tr>\n<th>2,5<\/th>\n<th>3<\/th>\n<td>\u226412,5<\/td>\n<th>8<\/th>\n<th>10<\/th>\n<td>\u226440<\/td>\n<\/tr>\n<tr>\n<th>3<\/th>\n<th>4<\/th>\n<td>\u226415<\/td>\n<th>10<\/th>\n<th>12<\/th>\n<td>\u226450<\/td>\n<\/tr>\n<tr>\n<th>4<\/th>\n<th>5<\/th>\n<td>\u226420<\/td>\n<th>12<\/th>\n<th>16<\/th>\n<td>\u226460<\/td>\n<\/tr>\n<tr>\n<th>5<\/th>\n<th>6<\/th>\n<td>\u226425<\/td>\n<th>16<\/th>\n<th>20<\/th>\n<td>\u226480<\/td>\n<\/tr>\n<tr>\n<th>6<\/th>\n<th>8<\/th>\n<td>\u226430<\/td>\n<th>20<\/th>\n<th>Nessuna restrizione<\/th>\n<td>\u2264100<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0747a26 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0747a26\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-45d1690\" data-id=\"45d1690\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c84ceb7 elementor-widget elementor-widget-text-editor\" data-id=\"c84ceb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed3c3d5 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"ed3c3d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th colspan=\"6\">Acciaio inossidabile<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center;\" colspan=\"2\">Larghezza<\/th>\n<th rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<th style=\"ext-align: center;\" colspan=\"2\">Larghezza<\/th>\n<th rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center;\">&gt;<\/th>\n<th style=\"text-align: center;\">\u2264<\/th>\n<th style=\"text-align: center;\">&gt;<\/th>\n<th style=\"text-align: center;\">\u2264<\/th>\n<\/tr>\n<tr>\n<th>2,5<\/th>\n<th>3<\/th>\n<td>\u226410<\/td>\n<th>8<\/th>\n<th>10<\/th>\n<td>\u226432<\/td>\n<\/tr>\n<tr>\n<th>3<\/th>\n<th>4<\/th>\n<td>\u226412<\/td>\n<th>10<\/th>\n<th>12<\/th>\n<td>\u226440<\/td>\n<\/tr>\n<tr>\n<th>4<\/th>\n<th>5<\/th>\n<td>\u226416<\/td>\n<th>12<\/th>\n<th>16<\/th>\n<td>\u226448<\/td>\n<\/tr>\n<tr>\n<th>5<\/th>\n<th>6<\/th>\n<td>\u226420<\/td>\n<th>16<\/th>\n<th>20<\/th>\n<td>\u226464<\/td>\n<\/tr>\n<tr>\n<th>6<\/th>\n<th>8<\/th>\n<td>\u226424<\/td>\n<th>20<\/th>\n<th>Nessuna restrizione<\/th>\n<td>\u226480<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0a4c51a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0a4c51a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a004b45\" data-id=\"a004b45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f42649 elementor-widget elementor-widget-text-editor\" data-id=\"2f42649\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f18f64b tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"f18f64b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th colspan=\"6\">Resina<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center;\" colspan=\"2\">Larghezza<\/th>\n<th rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<th style=\"ext-align: center;\" colspan=\"2\">Larghezza<\/th>\n<th rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center;\">&gt;<\/th>\n<th style=\"text-align: center;\">\u2264<\/th>\n<th style=\"text-align: center;\">&gt;<\/th>\n<th style=\"text-align: center;\">\u2264<\/th>\n<\/tr>\n<tr>\n<th>2,5<\/th>\n<th>3<\/th>\n<td>\u22647,5<\/td>\n<th>10<\/th>\n<th>12<\/th>\n<td>\u226430<\/td>\n<\/tr>\n<tr>\n<th>3<\/th>\n<th>4<\/th>\n<td>\u226410<\/td>\n<th>12<\/th>\n<th>18<\/th>\n<td>\u226440<\/td>\n<\/tr>\n<tr>\n<th>4<\/th>\n<th>6<\/th>\n<td>\u226415<\/td>\n<th>18<\/th>\n<th>Nessuna restrizione<\/th>\n<td>\u226460<\/td>\n<\/tr>\n<tr>\n<th>6<\/th>\n<th>10<\/th>\n<td>\u226420<\/td>\n<th colspan=\"3\">&#8211;<\/th>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a36ebf8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a36ebf8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ca2632e\" data-id=\"ca2632e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a943ab elementor-widget elementor-widget-text-editor\" data-id=\"2a943ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7417590 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"7417590\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th style=\"width: 97.3378%;\" colspan=\"6\">\n<ul>\n \t<li>Piatti lucidati<\/li>\n \t<li>(EN 1.0038  equiv. (barra piatta), EN 1.1191  equiv. (barra piatta), EN 1.4301  equiv. (barra piatta), EN AW-6063  equiv. (barra piatta))<\/li>\n<\/ul>\n<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center; width: 15.1414%;\" colspan=\"2\">Larghezza<\/th>\n<th style=\"width: 30.4493%;\" rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<th style=\"width: 21.2978%;\" colspan=\"2\">Larghezza<\/th>\n<th style=\"width: 30.4493%;\" rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center; width: 6.82196%;\">&gt;<\/th>\n<th style=\"text-align: center; width: 8.31947%;\">\u2264<\/th>\n<th style=\"text-align: center; width: 5.32446%;\">&gt;<\/th>\n<th style=\"text-align: center; width: 15.9734%;\">\u2264<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 6.82196%;\">2,5<\/th>\n<th style=\"width: 8.31947%;\">3<\/th>\n<td style=\"width: 30.4493%;\">\u226414<\/td>\n<th style=\"width: 5.32446%;\">8<\/th>\n<th style=\"width: 15.9734%;\">10<\/th>\n<td style=\"width: 30.4493%;\">\u226434<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 6.82196%;\">3<\/th>\n<th style=\"width: 8.31947%;\">4<\/th>\n<td style=\"width: 30.4493%;\">\u226417<\/td>\n<th style=\"width: 5.32446%;\">10<\/th>\n<th style=\"width: 15.9734%;\">12<\/th>\n<td style=\"width: 30.4493%;\">\u226444<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 6.82196%;\">4<\/th>\n<th style=\"width: 8.31947%;\">5<\/th>\n<td style=\"width: 30.4493%;\">\u226419<\/td>\n<th style=\"width: 5.32446%;\">12<\/th>\n<th style=\"width: 15.9734%;\">16<\/th>\n<td style=\"width: 30.4493%;\">\u226454<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 6.82196%;\">5<\/th>\n<th style=\"width: 8.31947%;\">6<\/th>\n<td style=\"width: 30.4493%;\">\u226422<\/td>\n<th style=\"width: 5.32446%;\">16<\/th>\n<th style=\"width: 15.9734%;\">20<\/th>\n<td style=\"width: 30.4493%;\">\u226464<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 6.82196%;\">6<\/th>\n<th style=\"width: 8.31947%;\">8<\/th>\n<td style=\"width: 30.4493%;\">\u226424<\/td>\n<th style=\"width: 5.32446%;\">20<\/th>\n<th style=\"width: 15.9734%;\">Nessuna restrizione<\/th>\n<td style=\"width: 30.4493%;\">\u226474<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-535ada6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"535ada6\" data-element_type=\"section\" data-e-type=\"section\" id=\"box_9\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a4016f2\" data-id=\"a4016f2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95f88ac elementor-widget elementor-widget-heading\" data-id=\"95f88ac\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"box_9\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fori asolati di precisione<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26ee5c5 elementor-widget elementor-widget-text-editor\" data-id=\"26ee5c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u00c8 possibile modificare un foro asolato in un foro asolato di precisione impostando il \u201cTipo di tolleranza del diametro del foro\u201d.\n\u00c8 possibile specificare la precisione per la direzione del passo dei fori asolati di precisione nei seguenti intervalli.\nLa tolleranza della profondit\u00e0 effettiva \u00e8 la profondit\u00e0 del modello,<img decoding=\"async\" src=\"\/help\/wp-content\/uploads\/2020\/01\/acy_fac_21.png\" alt=\"\" \/> indipendentemente dal passo.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c856b5e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c856b5e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-31e8c54\" data-id=\"31e8c54\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e14f3e3 elementor-widget elementor-widget-heading\" data-id=\"e14f3e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Intervalli di precisione specificabili<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98d93e9 elementor-widget elementor-widget-text-editor\" data-id=\"98d93e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d9d6c1 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"5d9d6c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th style=\"width: 20%;\" colspan=\"2\">Larghezza<\/th>\n<th style=\"width: 80%;\" colspan=\"3\">Intervalli di previsione<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 10%;\">&gt;<\/th>\n<th style=\"width: 10%;\">\u2264<\/th>\n<th style=\"width: 25.7732%;\">Tolleranza di accoppiamento<\/th>\n<th style=\"width: 17.5258%;\">Tolleranza bidirezionale minima<\/th>\n<th style=\"width: 34.0206%;\">Tolleranza unidirezionale minima<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 8.50515%;\">&#8211;<\/th>\n<th style=\"width: 10.567%;\">3<\/th>\n<td style=\"width: 25.7732%;\" rowspan=\"22\">Grado IT7 o superiore<\/td>\n<td>0,005<\/td>\n<td>0,01<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 8.50515%;\">3<\/th>\n<th style=\"width: 10.567%;\">6<\/th>\n<td>0,006<\/td>\n<td>0,012<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 8.50515%;\">6<\/th>\n<th style=\"width: 10.567%;\">10<\/th>\n<td>0,008<\/td>\n<td>0,015<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 8.50515%;\">10<\/th>\n<th style=\"width: 10.567%;\">18<\/th>\n<td>0,009<\/td>\n<td>0,018<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 8.50515%;\">18<\/th>\n<th style=\"width: 10.567%;\">30<\/th>\n<td>0,011<\/td>\n<td>0,021<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 8.50515%;\">30<\/th>\n<th style=\"width: 10.567%;\">50<\/th>\n<td>0,013<\/td>\n<td>0,025<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 8.50515%;\">50<\/th>\n<th style=\"width: 10.567%;\">80<\/th>\n<td>0,015<\/td>\n<td>0,03<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 8.50515%;\">80<\/th>\n<th style=\"width: 10.567%;\">120<\/th>\n<td>0,018<\/td>\n<td>0,035<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 8.50515%;\">120<\/th>\n<th style=\"width: 10.567%;\">180<\/th>\n<td>0,02<\/td>\n<td>0,04<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 8.50515%;\">180<\/th>\n<th style=\"width: 10.567%;\">250<\/th>\n<td>0,023<\/td>\n<td>0,046<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 8.50515%;\">250<\/th>\n<th style=\"width: 10.567%;\">315<\/th>\n<td>0,026<\/td>\n<td>0,052<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 8.50515%;\">315<\/th>\n<th style=\"width: 10.567%;\">400<\/th>\n<td>0,029<\/td>\n<td>0,057<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 8.50515%;\">400<\/th>\n<th style=\"width: 10.567%;\">500<\/th>\n<td>0,032<\/td>\n<td>0,063<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4cde2e3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4cde2e3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b0cb8eb\" data-id=\"b0cb8eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-885c8ae elementor-widget elementor-widget-heading\" data-id=\"885c8ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Profondit\u00e0 effettive preventivabili automaticamente<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9e867c elementor-widget elementor-widget-text-editor\" data-id=\"d9e867c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4602a4e tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"4602a4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th colspan=\"6\">Acciaio, Acciaio pre-temprato e acciaio per utensili<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center;\" colspan=\"2\">Larghezza<\/th>\n<th rowspan=\"2\">Profondit\u00e0 Efficace (Approssimativa)<\/th>\n<th style=\"ext-align: center;\" colspan=\"2\">Larghezza<\/th>\n<th rowspan=\"2\">Profondit\u00e0 Efficace (Approssimativa)<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center;\">&gt;<\/th>\n<th style=\"text-align: center;\">\u2264<\/th>\n<th style=\"text-align: center;\">&gt;<\/th>\n<th style=\"text-align: center;\">\u2264<\/th>\n<\/tr>\n<tr>\n<th>2,5<\/th>\n<th>3<\/th>\n<td>\u226410<\/td>\n<th>8<\/th>\n<th>10<\/th>\n<td>\u226440<\/td>\n<\/tr>\n<tr>\n<th>3<\/th>\n<th>4<\/th>\n<td>\u226412<\/td>\n<th>10<\/th>\n<th>12<\/th>\n<td>\u226450<\/td>\n<\/tr>\n<tr>\n<th>4<\/th>\n<th>5<\/th>\n<td>\u226416<\/td>\n<th>12<\/th>\n<th>16<\/th>\n<td>\u226460<\/td>\n<\/tr>\n<tr>\n<th>5<\/th>\n<th>6<\/th>\n<td>\u226420<\/td>\n<th>16<\/th>\n<th>20<\/th>\n<td>\u226480<\/td>\n<\/tr>\n<tr>\n<th>6<\/th>\n<th>8<\/th>\n<td>\u226430<\/td>\n<th>20<\/th>\n<th>Nessuna restrizione<\/th>\n<td>\u2264100<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dc99091 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dc99091\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-78414ae\" data-id=\"78414ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84cc4a8 elementor-widget elementor-widget-text-editor\" data-id=\"84cc4a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f64b9ca tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"f64b9ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th colspan=\"6\">Alluminio<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center;\" colspan=\"2\">Larghezza<\/th>\n<th rowspan=\"2\">Profondit\u00e0 Efficace (Approssimativa)\n<\/th>\n<th style=\"ext-align: center;\" colspan=\"2\">Larghezza<\/th>\n<th rowspan=\"2\">Profondit\u00e0 Efficace (Approssimativa)\n<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center;\">&gt;<\/th>\n<th style=\"text-align: center;\">\u2264<\/th>\n<th style=\"text-align: center;\">&gt;<\/th>\n<th style=\"text-align: center;\">\u2264<\/th>\n<\/tr>\n<tr>\n<th>2,5<\/th>\n<th>3<\/th>\n<td>\u226412,5<\/td>\n<th>8<\/th>\n<th>10<\/th>\n<td>\u226440<\/td>\n<\/tr>\n<tr>\n<th>3<\/th>\n<th>4<\/th>\n<td>\u226415<\/td>\n<th>10<\/th>\n<th>12<\/th>\n<td>\u226450<\/td>\n<\/tr>\n<tr>\n<th>4<\/th>\n<th>5<\/th>\n<td>\u226420<\/td>\n<th>12<\/th>\n<th>16<\/th>\n<td>\u226460<\/td>\n<\/tr>\n<tr>\n<th>5<\/th>\n<th>6<\/th>\n<td>\u226425<\/td>\n<th>16<\/th>\n<th>20<\/th>\n<td>\u226480<\/td>\n<\/tr>\n<tr>\n<th>6<\/th>\n<th>8<\/th>\n<td>\u226430<\/td>\n<th>20<\/th>\n<th>Nessuna restrizione<\/th>\n<td>\u2264100<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e40aac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e40aac\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d4f996a\" data-id=\"d4f996a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69f4c74 elementor-widget elementor-widget-text-editor\" data-id=\"69f4c74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8297e07 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"8297e07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th colspan=\"6\">Acciaio inossidabile<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center;\" colspan=\"2\">Larghezza<\/th>\n<th rowspan=\"2\">Profondit\u00e0 Efficace (Approssimativa)\n<\/th>\n<th style=\"ext-align: center;\" colspan=\"2\">Larghezza<\/th>\n<th rowspan=\"2\">Profondit\u00e0 Efficace (Approssimativa)\n<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center;\">&gt;<\/th>\n<th style=\"text-align: center;\">\u2264<\/th>\n<th style=\"text-align: center;\">&gt;<\/th>\n<th style=\"text-align: center;\">\u2264<\/th>\n<\/tr>\n<tr>\n<th>2,5<\/th>\n<th>3<\/th>\n<td>\u226410<\/td>\n<th>8<\/th>\n<th>10<\/th>\n<td>\u226432<\/td>\n<\/tr>\n<tr>\n<th>3<\/th>\n<th>4<\/th>\n<td>\u226412<\/td>\n<th>10<\/th>\n<th>12<\/th>\n<td>\u226440<\/td>\n<\/tr>\n<tr>\n<th>4<\/th>\n<th>5<\/th>\n<td>\u226416<\/td>\n<th>12<\/th>\n<th>16<\/th>\n<td>\u226448<\/td>\n<\/tr>\n<tr>\n<th>5<\/th>\n<th>6<\/th>\n<td>\u226420<\/td>\n<th>16<\/th>\n<th>20<\/th>\n<td>\u226464<\/td>\n<\/tr>\n<tr>\n<th>6<\/th>\n<th>8<\/th>\n<td>\u226424<\/td>\n<th>20<\/th>\n<th>Nessuna restrizione<\/th>\n<td>\u226480<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c626d81 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c626d81\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-28de5cf\" data-id=\"28de5cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-da76a31 elementor-widget elementor-widget-text-editor\" data-id=\"da76a31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2d5a21 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"e2d5a21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%; height: 189px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px; width: 97.3378%;\" colspan=\"6\">Resina<\/th>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px; width: 16.1398%;\" colspan=\"2\">Larghezza<\/th>\n<th style=\"height: 48px; width: 32.9451%;\" rowspan=\"2\">Profondit\u00e0 Efficace (Approssimativa)\n<\/th>\n<th style=\"height: 24px; width: 14.975%;\" colspan=\"2\">Larghezza<\/th>\n<th style=\"height: 48px; width: 33.2779%;\" rowspan=\"2\">Profondit\u00e0 Efficace (Approssimativa)\n<\/th>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"text-align: center; height: 24px; width: 7.15474%;\">&gt;<\/th>\n<th style=\"text-align: center; height: 24px; width: 8.98502%;\">\u2264<\/th>\n<th style=\"text-align: center; height: 24px; width: 5.99002%;\">&gt;<\/th>\n<th style=\"text-align: center; height: 24px; width: 8.98502%;\">\u2264<\/th>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px; width: 7.15474%;\">2,5<\/th>\n<th style=\"height: 24px; width: 8.98502%;\">3<\/th>\n<td>\u22645<\/td>\n<th style=\"height: 24px; width: 5.99002%;\">10<\/th>\n<th style=\"height: 24px; width: 8.98502%;\">12<\/th>\n<td>\u226420<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px; width: 7.15474%;\">3<\/th>\n<th style=\"height: 24px; width: 8.98502%;\">4<\/th>\n<td>\u22646<\/td>\n<th style=\"height: 24px; width: 5.99002%;\">12<\/th>\n<th style=\"height: 24px; width: 8.98502%;\">16<\/th>\n<td>\u226424<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"height: 21px; width: 7.15474%;\">4<\/th>\n<th style=\"height: 21px; width: 8.98502%;\">6<\/th>\n<td>\u22648<\/td>\n<th style=\"height: 21px; width: 5.99002%;\">16<\/th>\n<th style=\"height: 21px; width: 8.98502%;\">18<\/th>\n<td>\u226432<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px; width: 7.15474%;\">6<\/th>\n<th style=\"height: 24px; width: 8.98502%;\">8<\/th>\n<td>\u226412<\/td>\n<th style=\"height: 24px; width: 5.99002%;\">18<\/th>\n<th style=\"height: 24px; width: 8.98502%;\">20<\/th>\n<td>\u226436<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px; width: 7.15474%;\">8<\/th>\n<th style=\"height: 24px; width: 8.98502%;\">10<\/th>\n<td>\u226416<\/td>\n<th style=\"height: 24px; width: 5.99002%;\">20<\/th>\n<th style=\"width: 8.98502%; height: 24px;\">Nessuna restrizione<\/th>\n<td>\u226440<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6620256 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6620256\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1277f40\" data-id=\"1277f40\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1aca75 elementor-widget elementor-widget-text-editor\" data-id=\"b1aca75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbfb394 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"dbfb394\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%; height: 189px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px; width: 97.3378%;\" colspan=\"6\">\n<ul>\n \t<li>Piatti lucidati<\/li>\n \t<li>(EN 1.0038  equiv. (barra piatta), EN 1.1191  equiv. (barra piatta), EN 1.4301  equiv. (barra piatta), EN AW-6063  equiv. (barra piatta))<\/li>\n<\/ul>\n<\/th>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px; width: 16.1398%;\" colspan=\"2\">Larghezza<\/th>\n<th style=\"height: 48px; width: 32.9451%;\" rowspan=\"2\">Profondit\u00e0 Efficace (Approssimativa)<\/th>\n<th style=\"height: 24px; width: 14.975%;\" colspan=\"2\">Larghezza<\/th>\n<th style=\"height: 48px; width: 33.2779%;\" rowspan=\"2\">Profondit\u00e0 Efficace (Approssimativa)<\/th>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"text-align: center; height: 24px; width: 7.15474%;\">&gt;<\/th>\n<th style=\"text-align: center; height: 24px; width: 8.98502%;\">\u2264<\/th>\n<th style=\"text-align: center; height: 24px; width: 5.99002%;\">&gt;<\/th>\n<th style=\"text-align: center; height: 24px; width: 8.98502%;\">\u2264<\/th>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px; width: 7.15474%;\">2,5<\/th>\n<th style=\"height: 24px; width: 8.98502%;\">3<\/th>\n<td style=\"height: 24px; width: 32.9451%;\">\u22647<\/td>\n<th style=\"height: 24px; width: 5.99002%;\">8<\/th>\n<th style=\"height: 24px; width: 8.98502%;\">10<\/th>\n<td style=\"height: 24px; width: 33.2779%;\">\u226431<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px; width: 7.15474%;\">3<\/th>\n<th style=\"height: 24px; width: 8.98502%;\">4<\/th>\n<td style=\"height: 24px; width: 32.9451%;\">\u226411<\/td>\n<th style=\"height: 24px; width: 5.99002%;\">10<\/th>\n<th style=\"height: 24px; width: 8.98502%;\">12<\/th>\n<td style=\"height: 24px; width: 33.2779%;\">\u226439<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 7.15474%;\">4<\/th>\n<th style=\"width: 8.98502%;\">5<\/th>\n<td style=\"width: 32.9451%;\">\u226415<\/td>\n<th style=\"width: 5.99002%;\">12<\/th>\n<th style=\"width: 8.98502%;\">16<\/th>\n<td style=\"width: 33.2779%;\">\u226447<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"height: 21px; width: 7.15474%;\">5<\/th>\n<th style=\"height: 21px; width: 8.98502%;\">6<\/th>\n<td style=\"height: 21px; width: 32.9451%;\">\u226419<\/td>\n<th style=\"height: 21px; width: 5.99002%;\">16<\/th>\n<th style=\"height: 21px; width: 8.98502%;\">20<\/th>\n<td style=\"height: 21px; width: 33.2779%;\">\u226463<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px; width: 7.15474%;\">6<\/th>\n<th style=\"height: 24px; width: 8.98502%;\">8<\/th>\n<td style=\"height: 24px; width: 32.9451%;\">\u226423<\/td>\n<th style=\"height: 24px; width: 5.99002%;\">20<\/th>\n<th style=\"height: 24px; width: 8.98502%;\">Nessuna restrizione<\/th>\n<td style=\"height: 24px; width: 33.2779%;\">\u226473<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a04bfb7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a04bfb7\" data-element_type=\"section\" data-e-type=\"section\" id=\"box_10\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0deb93e\" data-id=\"0deb93e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3555cf elementor-widget elementor-widget-heading\" data-id=\"d3555cf\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"box_10\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tasche<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c28026a elementor-widget elementor-widget-text-editor\" data-id=\"c28026a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tutti i punti di lavorazione che non rientrano nella categoria dei fori o dei fori asolati sono classificati come tasche.<br \/>Le tasche hanno anche un intervallo di quotazione automatica per larghezza, profondit\u00e0 e dimensione R (se presente).<br \/>Per le forme con uno smusso di C15 o inferiore che possono essere lavorate con una fresa per smussare, non vi \u00e8 alcun limite di profondit\u00e0.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4d37a28 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4d37a28\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-daad74c\" data-id=\"daad74c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9966a01 elementor-widget elementor-widget-heading\" data-id=\"9966a01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Tabella di compatibilit\u00e0 larghezza\/profondit\u00e0 tasca<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df19ff3 elementor-widget elementor-widget-text-editor\" data-id=\"df19ff3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a98228 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"8a98228\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th style=\"width: 97.3378%;\" colspan=\"6\">Acciaio, Acciaio pre-temprato e acciaio per utensili<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center; width: 14.975%;\" colspan=\"2\">Larghezza<\/th>\n<th style=\"width: 30.2829%;\" rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<th style=\"width: 21.6306%;\" colspan=\"2\">Larghezza<\/th>\n<th style=\"width: 30.4493%;\" rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center; width: 6.65557%;\">&gt;<\/th>\n<th style=\"text-align: center; width: 8.31947%;\">\u2264<\/th>\n<th style=\"text-align: center; width: 5.99002%;\">&gt;<\/th>\n<th style=\"text-align: center; width: 15.6406%;\">\u2264<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 6.65557%;\">2,5<\/th>\n<th style=\"width: 8.31947%;\">3<\/th>\n<td>\u226410<\/td>\n<th style=\"width: 5.99002%;\">8<\/th>\n<th style=\"width: 15.6406%;\">10<\/th>\n<td>\u226440<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 6.65557%;\">3<\/th>\n<th style=\"width: 8.31947%;\">4<\/th>\n<td>\u226412<\/td>\n<th style=\"width: 5.99002%;\">10<\/th>\n<th style=\"width: 15.6406%;\">12<\/th>\n<td>\u226450<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 6.65557%;\">4<\/th>\n<th style=\"width: 8.31947%;\">5<\/th>\n<td>\u226416<\/td>\n<th style=\"width: 5.99002%;\">12<\/th>\n<th style=\"width: 15.6406%;\">16<\/th>\n<td>\u226460<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 6.65557%;\">5<\/th>\n<th style=\"width: 8.31947%;\">6<\/th>\n<td>\u226420<\/td>\n<th style=\"width: 5.99002%;\">16<\/th>\n<th style=\"width: 15.6406%;\">20<\/th>\n<td>\u226480<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 6.65557%;\">6<\/th>\n<th style=\"width: 8.31947%;\">8<\/th>\n<td>\u226430<\/td>\n<th style=\"width: 5.99002%;\">20<\/th>\n<th style=\"width: 15.6406%;\">Nessuna restrizione<\/th>\n<td>\u2264100<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0ffe449 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0ffe449\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-85b529f\" data-id=\"85b529f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3ce856 elementor-widget elementor-widget-text-editor\" data-id=\"a3ce856\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa9152e tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"fa9152e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th style=\"width: 97.3378%;\" colspan=\"6\">Alluminio<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center; width: 14.975%;\" colspan=\"2\">Larghezza<\/th>\n<th style=\"width: 30.2829%;\" rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<th style=\"width: 21.6306%;\" colspan=\"2\">Larghezza<\/th>\n<th style=\"width: 30.4493%;\" rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center; width: 6.65557%;\">&gt;<\/th>\n<th style=\"text-align: center; width: 8.31947%;\">\u2264<\/th>\n<th style=\"text-align: center; width: 5.99002%;\">&gt;<\/th>\n<th style=\"text-align: center; width: 15.6406%;\">\u2264<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 6.65557%;\">2,5<\/th>\n<th style=\"width: 8.31947%;\">3<\/th>\n<td>\u226412,5<\/td>\n<th style=\"width: 5.99002%;\">8<\/th>\n<th style=\"width: 15.6406%;\">10<\/th>\n<td>\u226440<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 6.65557%;\">3<\/th>\n<th style=\"width: 8.31947%;\">4<\/th>\n<td>\u226415<\/td>\n<th style=\"width: 5.99002%;\">10<\/th>\n<th style=\"width: 15.6406%;\">12<\/th>\n<td>\u226450<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 6.65557%;\">4<\/th>\n<th style=\"width: 8.31947%;\">5<\/th>\n<td>\u226420<\/td>\n<th style=\"width: 5.99002%;\">12<\/th>\n<th style=\"width: 15.6406%;\">16<\/th>\n<td>\u226460<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 6.65557%;\">5<\/th>\n<th style=\"width: 8.31947%;\">6<\/th>\n<td>\u226425<\/td>\n<th style=\"width: 5.99002%;\">16<\/th>\n<th style=\"width: 15.6406%;\">20<\/th>\n<td>\u226480<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 6.65557%;\">6<\/th>\n<th style=\"width: 8.31947%;\">8<\/th>\n<td>\u226430<\/td>\n<th style=\"width: 5.99002%;\">20<\/th>\n<th style=\"width: 15.6406%;\">Nessuna restrizione<\/th>\n<td>\u2264100<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-978af35 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"978af35\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-85d7912\" data-id=\"85d7912\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4290561 elementor-widget elementor-widget-text-editor\" data-id=\"4290561\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3554324 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"3554324\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th style=\"width: 97.3379%;\" colspan=\"6\">Acciaio inossidabile<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center; width: 14.975%;\" colspan=\"2\">Larghezza<\/th>\n<th style=\"width: 30.2829%;\" rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<th style=\"width: 21.6306%;\" colspan=\"2\">Larghezza<\/th>\n<th style=\"width: 30.4493%;\" rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center; width: 6.65557%;\">&gt;<\/th>\n<th style=\"text-align: center; width: 8.31947%;\">\u2264<\/th>\n<th style=\"text-align: center; width: 5.99002%;\">&gt;<\/th>\n<th style=\"text-align: center; width: 15.6406%;\">\u2264<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 6.65557%;\">2,5<\/th>\n<th style=\"width: 8.31947%;\">3<\/th>\n<td>\u226410<\/td>\n<th style=\"width: 5.99002%;\">8<\/th>\n<th style=\"width: 15.6406%;\">10<\/th>\n<td>\u226432<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 6.65557%;\">3<\/th>\n<th style=\"width: 8.31947%;\">4<\/th>\n<td>\u226412<\/td>\n<th style=\"width: 5.99002%;\">10<\/th>\n<th style=\"width: 15.6406%;\">12<\/th>\n<td>\u226440<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 6.65557%;\">4<\/th>\n<th style=\"width: 8.31947%;\">5<\/th>\n<td>\u226416<\/td>\n<th style=\"width: 5.99002%;\">12<\/th>\n<th style=\"width: 15.6406%;\">16<\/th>\n<td>\u226448<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 6.65557%;\">5<\/th>\n<th style=\"width: 8.31947%;\">6<\/th>\n<td>\u226420<\/td>\n<th style=\"width: 5.99002%;\">16<\/th>\n<th style=\"width: 15.6406%;\">20<\/th>\n<td>\u226464<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 6.65557%;\">6<\/th>\n<th style=\"width: 8.31947%;\">8<\/th>\n<td>\u226424<\/td>\n<th style=\"width: 5.99002%;\">20<\/th>\n<th style=\"width: 15.6406%;\">Nessuna restrizione<\/th>\n<td>\u226480<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-162db48 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"162db48\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-de13621\" data-id=\"de13621\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7cc106f elementor-widget elementor-widget-text-editor\" data-id=\"7cc106f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb8f30e tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"bb8f30e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%; height: 168px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px; width: 97.3378%;\" colspan=\"6\">Resina<\/th>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px; width: 16.1398%;\" colspan=\"2\">Larghezza<\/th>\n<th style=\"height: 48px; width: 32.9451%;\" rowspan=\"2\">Profondit\u00e0 Efficace (Approssimativa)\n<\/th>\n<th style=\"height: 24px; width: 14.975%;\" colspan=\"2\">Larghezza<\/th>\n<th style=\"height: 48px; width: 33.2779%;\" rowspan=\"2\">Profondit\u00e0 Efficace (Approssimativa)\n<\/th>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"text-align: center; height: 24px; width: 7.15474%;\">&gt;<\/th>\n<th style=\"text-align: center; height: 24px; width: 8.98502%;\">\u2264<\/th>\n<th style=\"text-align: center; height: 24px; width: 5.99002%;\">&gt;<\/th>\n<th style=\"text-align: center; height: 24px; width: 8.98502%;\">\u2264<\/th>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px; width: 7.15474%;\">2,5<\/th>\n<th style=\"height: 24px; width: 8.98502%;\">3<\/th>\n<td>\u22647,5<\/td>\n<th style=\"height: 24px; width: 5.99002%;\">10<\/th>\n<th style=\"height: 24px; width: 8.98502%;\">12<\/th>\n<td>\u226430<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px; width: 7.15474%;\">3<\/th>\n<th style=\"height: 24px; width: 8.98502%;\">4<\/th>\n<td>\u226410<\/td>\n<th style=\"height: 24px; width: 5.99002%;\">12<\/th>\n<th style=\"height: 24px; width: 8.98502%;\">18<\/th>\n<td>\u226440<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px; width: 7.15474%;\">4<\/th>\n<th style=\"height: 24px; width: 8.98502%;\">6<\/th>\n<td>\u226415<\/td>\n<th style=\"height: 24px; width: 5.99002%;\">18<\/th>\n<th style=\"height: 24px; width: 8.98502%;\">Nessuna restrizione<\/th>\n<td>\u226460<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"height: 24px; width: 7.15474%;\">6<\/th>\n<th style=\"height: 24px; width: 8.98502%;\">10<\/th>\n<td>\u226420<\/td>\n<th><\/th>\n<th><\/th>\n<th><\/th>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ce7df0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ce7df0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66d7c45\" data-id=\"66d7c45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-941adcf elementor-widget elementor-widget-heading\" data-id=\"941adcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Tabella di compatibilit\u00e0 R delle tasche \/altezza<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d003f2 elementor-widget elementor-widget-text-editor\" data-id=\"3d003f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73ad4cd tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"73ad4cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%; height: 192px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<th style=\"width: 97.4109%; height: 24px;\" colspan=\"6\">Acciaio, Acciaio pre-temprato e acciaio per utensili\n<\/th>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"text-align: center; width: 19.0938%; height: 24px;\" colspan=\"2\">R<\/th>\n<th style=\"width: 28.9644%; height: 48px;\" rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<th style=\"width: 20.0647%; height: 24px;\" colspan=\"2\">R<\/th>\n<th style=\"width: 29.288%; height: 48px;\" rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"text-align: center; width: 11.165%; height: 24px;\">&gt;<\/th>\n<th style=\"text-align: center; width: 7.9288%; height: 24px;\">\u2264<\/th>\n<th style=\"text-align: center; width: 5.01618%; height: 24px;\">&gt;<\/th>\n<th style=\"text-align: center; width: 15.0485%; height: 24px;\">\u2264<\/th>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"width: 11.165%; height: 24px;\">0,74<\/th>\n<th style=\"width: 7.9288%; height: 24px;\">1,5<\/th>\n<td>\u226415<\/td>\n<th style=\"width: 5.01618%; height: 24px;\">5<\/th>\n<th style=\"width: 15.0485%; height: 24px;\">6<\/th>\n<td>\u226450<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"width: 11.165%; height: 24px;\">1,5<\/th>\n<th style=\"width: 7.9288%; height: 24px;\">3<\/th>\n<td>\u226420<\/td>\n<th style=\"width: 5.01618%; height: 24px;\">6<\/th>\n<th style=\"width: 15.0485%; height: 24px;\">8<\/th>\n<td>\u226460<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"width: 11.165%; height: 24px;\">3<\/th>\n<th style=\"width: 7.9288%; height: 24px;\">4<\/th>\n<td>\u226430<\/td>\n<th style=\"width: 5.01618%; height: 24px;\">8<\/th>\n<th style=\"width: 15.0485%; height: 24px;\">10<\/th>\n<td>\u226480<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<th style=\"width: 11.165%; height: 24px;\">4<\/th>\n<th style=\"width: 7.9288%; height: 24px;\">5<\/th>\n<td>\u226440<\/td>\n<th style=\"width: 5.01618%; height: 24px;\">10<\/th>\n<th style=\"width: 15.0485%; height: 24px;\">Nessuna restrizione<\/th>\n<td>\u2264100<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d4c2a65 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d4c2a65\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-82365c8\" data-id=\"82365c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-274bc91 elementor-widget elementor-widget-text-editor\" data-id=\"274bc91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c86deb3 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"c86deb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th style=\"width: 97.4109%;\" colspan=\"6\">Alluminio<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center; width: 19.0938%;\" colspan=\"2\">R<\/th>\n<th style=\"width: 28.9644%;\" rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<th style=\"width: 20.0647%;\" colspan=\"2\">R<\/th>\n<th style=\"width: 29.288%;\" rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center; width: 11.165%;\">&gt;<\/th>\n<th style=\"text-align: center; width: 7.9288%;\">\u2264<\/th>\n<th style=\"text-align: center; width: 5.01618%;\">&gt;<\/th>\n<th style=\"text-align: center; width: 15.0485%;\">\u2264<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 11.165%;\">0,74<\/th>\n<th style=\"width: 7.9288%;\">1,5<\/th>\n<td>\u226415<\/td>\n<th style=\"width: 5.01618%;\">5<\/th>\n<th style=\"width: 15.0485%;\">6<\/th>\n<td>\u226450<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 11.165%;\">1,5<\/th>\n<th style=\"width: 7.9288%;\">3<\/th>\n<td>\u226420<\/td>\n<th style=\"width: 5.01618%;\">6<\/th>\n<th style=\"width: 15.0485%;\">8<\/th>\n<td>\u226460<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 11.165%;\">3<\/th>\n<th style=\"width: 7.9288%;\">4<\/th>\n<td>\u226430<\/td>\n<th style=\"width: 5.01618%;\">8<\/th>\n<th style=\"width: 15.0485%;\">10<\/th>\n<td>\u226480<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 11.165%;\">4<\/th>\n<th style=\"width: 7.9288%;\">5<\/th>\n<td>\u226440<\/td>\n<th style=\"width: 5.01618%;\">10<\/th>\n<th style=\"width: 15.0485%;\">Nessuna restrizione<\/th>\n<td>\u2264150<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5e1e57d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5e1e57d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9dd6aff\" data-id=\"9dd6aff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d31928 elementor-widget elementor-widget-text-editor\" data-id=\"9d31928\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef63505 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"ef63505\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th style=\"width: 97.4109%;\" colspan=\"6\">Acciaio inossidabile<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center; width: 19.0938%;\" colspan=\"2\">R<\/th>\n<th style=\"width: 28.9644%;\" rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<th style=\"width: 20.0647%;\" colspan=\"2\">R<\/th>\n<th style=\"width: 29.288%;\" rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center; width: 11.165%;\">&gt;<\/th>\n<th style=\"text-align: center; width: 7.9288%;\">\u2264<\/th>\n<th style=\"text-align: center; width: 5.01618%;\">&gt;<\/th>\n<th style=\"text-align: center; width: 15.0485%;\">\u2264<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 11.165%;\">0,74<\/th>\n<th style=\"width: 7.9288%;\">1,5<\/th>\n<td>\u226415<\/td>\n<th style=\"width: 5.01618%;\">5<\/th>\n<th style=\"width: 15.0485%;\">6<\/th>\n<td>\u226440<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 11.165%;\">1.5<\/th>\n<th style=\"width: 7.9288%;\">3<\/th>\n<td>\u226420<\/td>\n<th style=\"width: 5.01618%;\">6<\/th>\n<th style=\"width: 15.0485%;\">8<\/th>\n<td>\u226448<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 11.165%;\">3<\/th>\n<th style=\"width: 7.9288%;\">4<\/th>\n<td>\u226424<\/td>\n<th style=\"width: 5.01618%;\">8<\/th>\n<th style=\"width: 15.0485%;\">10<\/th>\n<td>\u226464<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 11.165%;\">4<\/th>\n<th style=\"width: 7.9288%;\">5<\/th>\n<td>\u226432<\/td>\n<th style=\"width: 5.01618%;\">10<\/th>\n<th style=\"width: 15.0485%;\">Nessuna restrizione<\/th>\n<td>\u226480<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d3bd9c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d3bd9c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-418b902\" data-id=\"418b902\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b3e0e6d elementor-widget elementor-widget-text-editor\" data-id=\"b3e0e6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">[mm]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e3f720 tblBasic elementor-widget elementor-widget-text-editor\" data-id=\"2e3f720\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th style=\"width: 101.404%;\" colspan=\"6\">Resina<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center; width: 19.0938%;\" colspan=\"2\">R<\/th>\n<th rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<th style=\"width: 20.0647%;\" colspan=\"2\">R<\/th>\n<th rowspan=\"2\">Profondit\u00e0 di lavorazione (approssimativa)<\/th>\n<\/tr>\n<tr>\n<th style=\"text-align: center; width: 11.165%;\">&gt;<\/th>\n<th style=\"text-align: center; width: 7.9288%;\">\u2264<\/th>\n<th style=\"text-align: center; width: 5.01618%;\">&gt;<\/th>\n<th style=\"text-align: center; width: 15.0485%;\">\u2264<\/th>\n<\/tr>\n<tr>\n<th style=\"width: 11.165%;\">1,249<\/th>\n<th style=\"width: 7.9288%;\">1,5<\/th>\n<td>\u22647,5<\/td>\n<th style=\"width: 5.01618%;\">5<\/th>\n<th style=\"width: 15.0485%;\">6<\/th>\n<td>\u226430<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 11.165%;\">1,5<\/th>\n<th style=\"width: 7.9288%;\">2<\/th>\n<td>\u226410<\/td>\n<th style=\"width: 5.01618%;\">6<\/th>\n<th style=\"width: 15.0485%;\">10<\/th>\n<td>\u226440<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 11.165%;\">2<\/th>\n<th style=\"width: 7.9288%;\">3<\/th>\n<td>\u226415<\/td>\n<th style=\"width: 5.01618%;\">10<\/th>\n<th style=\"width: 15.0485%;\">Nessuna restrizione<\/th>\n<td>\u226450<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 11.165%;\">3<\/th>\n<th style=\"width: 7.9288%;\">5<\/th>\n<td>\u226420<\/td>\n<th style=\"width: 5.01618%;\"><\/th>\n<th style=\"width: 15.0485%;\"><\/th>\n<th><\/th>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Fori cilindrici\u3000| Intervalli di precisione quotabili automaticamente\u00a0 | Fori filettati\u00a0 | Fori con inserto\u00a0 | Fori a 1 scalino\u00a0 | Fori a 2 scalini\u00a0 | Fori svasati\u00a0 | Fori asolati\u00a0 | Fori asolati di precisione\u00a0 | Tasche Fori cilindrici I fori realizzati con punte o frese non soggetti a tolleranze di precisione specifiche sono denominati &#8220;fori cilindrici&#8221; nei servizi di lavorazione. Gli utensili utilizzati hanno differenti profondit\u00e0 di lavorazione preventivabili automaticamente. Il valore massimo indicato \u00e8 da considerarsi approssimativo. Tale valore pu\u00f2 variare a seconda di altri fattori indicati in fase di preventivo, come geometria o materiale. Grazie per la comprensione. Lavorazione con punta [mm] Acciaio, Acciaio pre-temprato e acciaio [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[254],"tags":[245],"class_list":["post-39856","post","type-post","status-publish","format-standard","hentry","category-mpb_conditions-it-c","tag-technical_mpb-it"],"views":24,"_links":{"self":[{"href":"https:\/\/de.meviy.misumi-ec.com\/help\/it\/wp-json\/wp\/v2\/posts\/39856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/de.meviy.misumi-ec.com\/help\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/de.meviy.misumi-ec.com\/help\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/de.meviy.misumi-ec.com\/help\/it\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/de.meviy.misumi-ec.com\/help\/it\/wp-json\/wp\/v2\/comments?post=39856"}],"version-history":[{"count":44,"href":"https:\/\/de.meviy.misumi-ec.com\/help\/it\/wp-json\/wp\/v2\/posts\/39856\/revisions"}],"predecessor-version":[{"id":89455,"href":"https:\/\/de.meviy.misumi-ec.com\/help\/it\/wp-json\/wp\/v2\/posts\/39856\/revisions\/89455"}],"wp:attachment":[{"href":"https:\/\/de.meviy.misumi-ec.com\/help\/it\/wp-json\/wp\/v2\/media?parent=39856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/de.meviy.misumi-ec.com\/help\/it\/wp-json\/wp\/v2\/categories?post=39856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/de.meviy.misumi-ec.com\/help\/it\/wp-json\/wp\/v2\/tags?post=39856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}