{"id":39940,"date":"2020-01-20T17:32:56","date_gmt":"2020-01-20T08:32:56","guid":{"rendered":"https:\/\/de.meviy.misumi-ec.com\/help\/non-categorizzato\/39940\/"},"modified":"2025-12-16T17:37:34","modified_gmt":"2025-12-16T08:37:34","slug":"%e6%9b%b2%e3%81%92%e5%8a%a0%e5%b7%a5%e3%81%ae%e5%b9%b2%e6%b8%89-%e3%82%b3%e3%81%ae%e5%ad%97%e6%9b%b2%e3%81%92%e3%83%bb%e6%ae%b5%e6%9b%b2%e3%81%92z%e6%9b%b2%e3%81%92%e3%81%ae%e8%a8%ad%e8%a8%88","status":"publish","type":"post","link":"https:\/\/de.meviy.misumi-ec.com\/help\/it\/technical_info-it-c\/shm_conditions-it-c\/39940\/","title":{"rendered":"Specifiche di curvabilit\u00e0"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"39940\" class=\"elementor elementor-39940 elementor-9703\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-374c08a3 tblBasic elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"374c08a3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-15cb8878\" data-id=\"15cb8878\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09d90b8 elementor-widget elementor-widget-heading\" data-id=\"09d90b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Specifiche di curvabilit\u00e0<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b7504d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b7504d5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c634ad4\" data-id=\"c634ad4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47f4e1d elementor-widget elementor-widget-heading\" data-id=\"47f4e1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Curvatura normale<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7314a97 elementor-widget elementor-widget-text-editor\" data-id=\"7314a97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th style=\"width: 8%;\">No.<\/th>\n<th style=\"width: 26%;\">Parte standard<\/th>\n<th style=\"width: 26%;\">Valore standard<\/th>\n<th style=\"width: 40%;\">Esempio<\/th>\n<\/tr>\n<tr>\n<th><span style=\"background: #40ca57; padding: .3em .5em; color: #fff;\">1<\/span><\/th>\n<td style=\"text-align: left;\">Tolleranza angolo di curvatura<\/td>\n<td style=\"text-align: left;\">\n<ul>\n \t<li>Linea di prodotti: Standard \/ International Economy<\/li>\n \t<li>Spessore della lamina \u226410,0 mm: \u00b11,0\u00b0<\/li>\n \t<li>Spessore della lamina &gt;10,0 mm: \u00b11,5\u00b0<\/li>\n<\/ul>\n<\/td>\n<td rowspan=\"3\"><img decoding=\"async\" src=\"\/help\/wp-content\/uploads\/2020\/01\/fcpl_item_accuracy_2.png\" alt=\"Esempio\" width=\"228\" height=\"194\" \/><\/td>\n<\/tr>\n<tr>\n<th><span style=\"background: #40ca57; padding: .3em .5em; color: #fff;\">2<\/span><\/th>\n<td style=\"text-align: left;\">Raggio interno (r)<\/td>\n<td style=\"text-align: left;\">Spessore della lamina (valore di riferimento)<\/td>\n<\/tr>\n<tr>\n<th><span style=\"background: #40ca57; padding: .3em .5em; color: #fff;\">3<\/span><\/th>\n<td style=\"text-align: left;\">Raggio esterno (R)<\/td>\n<td style=\"text-align: left;\">R = spessore della lamina \u00d7 2 (valore di riferimento)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9b45161 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9b45161\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-eec01f1\" data-id=\"eec01f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-893239f elementor-widget elementor-widget-heading\" data-id=\"893239f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Forma di curvatura a R (curvatura FR)<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-349c9ca elementor-widget elementor-widget-text-editor\" data-id=\"349c9ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th style=\"width: 8%;\">No.<\/th>\n<th style=\"width: 26%;\">Parte standard<\/th>\n<th style=\"width: 26%;\">Valore standard<\/th>\n<th style=\"width: 40%;\">Esempio<\/th>\n<\/tr>\n<tr>\n<th><span style=\"background: #40ca57; padding: .3em .5em; color: #fff;\">1<\/span><\/th>\n<td style=\"text-align: left;\">Tolleranza angolo di curvatura<\/td>\n<td style=\"text-align: left;\">\n<ul>\n \t<li>\u00b12,0\u00b0<\/li>\n \t<li><\/li>\n<\/ul>\n<\/td>\n<td rowspan=\"3\"><img decoding=\"async\" src=\"\/help\/wp-content\/uploads\/2021\/09\/3445_01_EN.png\" alt=\"Esempio\" width=\"228\" height=\"194\" \/><\/td>\n<\/tr>\n<tr>\n<th><span style=\"background: #40ca57; padding: .3em .5em; color: #fff;\">2<\/span><\/th>\n<td style=\"text-align: left;\">R interno<\/td>\n<td style=\"text-align: left;\">Dimensioni di modellazione (valore di riferimento)<\/td>\n<\/tr>\n<tr>\n<th><span style=\"background: #40ca57; padding: .3em .5em; color: #fff;\">3<\/span><\/th>\n<td style=\"text-align: left;\">R esterno<\/td>\n<td style=\"text-align: left;\">R interno + spessore della lamina (valore di riferimento)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5145e93 tblBasic elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5145e93\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-19a492b\" data-id=\"19a492b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-de84203 elementor-widget elementor-widget-heading\" data-id=\"de84203\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sporgenze dovute alla curvabilit\u00e0<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f096d77 elementor-widget elementor-widget-text-editor\" data-id=\"f096d77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<th style=\"width: 60%;\">Valore standard<\/th>\n<th style=\"width: 40%;\">Esempio<\/th>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">Come mostrato nell&#8217;esempio a destra, possono verificarsi rigonfiamenti\/sporgenze pari a circa il 15% dello spessore della lamina su ciascun lato.<\/td>\n<td><img decoding=\"async\" src=\"\/help\/wp-content\/uploads\/2025\/07\/39940_01_deIT.png\" alt=\"Esempio\" width=\"245\" height=\"109\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7613c33 tblBasic elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7613c33\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3db7bca\" data-id=\"3db7bca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3e0c12 elementor-widget elementor-widget-heading\" data-id=\"d3e0c12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Difetti causati dalla curvatura<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0163149 elementor-widget elementor-widget-text-editor\" data-id=\"0163149\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%;\"><tbody><tr><th style=\"width: 60%;\">Valore standard<\/th><th style=\"width: 40%;\">Esempio<\/th><\/tr><tr><td style=\"text-align: left;\">Come mostrato nell&#8217;esempio a destra, si sono verificati difetti nella matrice piegata.<\/td><td><img loading=\"lazy\" decoding=\"async\" src=\"\/help\/wp-content\/uploads\/2020\/01\/fcpl_item_accuracy_11.png\" alt=\"Esempio\" width=\"221\" height=\"134\" \/><\/td><\/tr><tr><td style=\"text-align: left;\">Poich\u00e9 viene lavorato come piegatura FR (piegatura con avanzamento), sulla parte piegata a R rimarranno dei segni dello stampo.<\/td><td><table style=\"border: 0; margin-top: 0; height: 131px; width: 100%; border-collapse: collapse;\"><tbody><tr style=\"height: 24px;\"><td style=\"width: 50%; border: none; text-align: left; height: 24px;\" colspan=\"2\">\u25a0Senza trattamento superficiale (EN AW-5052 equiv.)<\/td><\/tr><tr style=\"height: 24px;\"><td style=\"width: 50%; border: none; height: 24px; text-align: center;\">Curvatura interna<\/td><td style=\"width: 50%; border: none; height: 24px; text-align: center;\">Curvatura esterna<\/td><\/tr><tr style=\"height: 126px;\"><td style=\"width: 50%; border: none; height: 20px;\"><img decoding=\"async\" src=\"https:\/\/jp.meviy.misumi-ec.com\/help\/ja\/wp-content\/uploads\/2021\/09\/3445_02.png\" alt=\"\" \/><\/td><td style=\"width: 50%; border: none; height: 20px;\"><img decoding=\"async\" src=\"https:\/\/jp.meviy.misumi-ec.com\/help\/ja\/wp-content\/uploads\/2021\/09\/3445_03.png\" alt=\"\" \/><\/td><\/tr><tr style=\"height: 29px;\"><td style=\"width: 50%; border: none; text-align: left; height: 29px;\" colspan=\"2\">\u25a0Verniciatura<\/td><\/tr><tr style=\"height: 24px;\"><td style=\"width: 50%; border: none; height: 24px; text-align: center;\">Curva interna<\/td><td style=\"width: 50%; border: none; height: 24px; text-align: center;\">Curva esterna<\/td><\/tr><tr style=\"height: 98px;\"><td style=\"width: 50%; border: none; height: 10px;\"><img decoding=\"async\" src=\"https:\/\/jp.meviy.misumi-ec.com\/help\/ja\/wp-content\/uploads\/2021\/09\/3445_04.png\" alt=\"\" \/><\/td><td style=\"width: 50%; border: none; height: 10px;\"><img decoding=\"async\" src=\"https:\/\/jp.meviy.misumi-ec.com\/help\/ja\/wp-content\/uploads\/2021\/09\/3445_05.png\" alt=\"\" \/><\/td><\/tr><\/tbody><\/table><\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cabc8a1 tblBasic elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cabc8a1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c53a29\" data-id=\"2c53a29\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be4738b elementor-widget elementor-widget-heading\" data-id=\"be4738b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Crepe causate dalla curvabilit\u00e0 (EN AW-5052 equiv.)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e10c1ee elementor-widget elementor-widget-text-editor\" data-id=\"e10c1ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"tableHover_single\" style=\"width: 100%;\"><tbody><tr><th style=\"width: 60%;\">Valore standard<\/th><th style=\"width: 40%;\">Esempio<\/th><\/tr><tr><td style=\"text-align: left;\">EN AW-5052 equiv. presenterebbe una leggera crepa se piegato a causa delle propriet\u00e0 del materiale.<\/td><td><ul><li style=\"text-align: left; margin-bottom: 1rem;\">\u25a0EN AW-5052 equiv. (Spessore: 6,0 mm)<\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"\/help\/wp-content\/uploads\/2022\/09\/3445_06.png\" alt=\"Beispiel\" width=\"245\" height=\"109\" \/><\/li><\/ul><\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Specifiche di curvabilit\u00e0 Curvatura normale No. Parte standard Valore standard Esempio 1 Tolleranza angolo di curvatura Linea di prodotti: Standard \/ International Economy Spessore della lamina \u226410,0 mm: \u00b11,0\u00b0 Spessore della lamina &gt;10,0 mm: \u00b11,5\u00b0 2 Raggio interno (r) Spessore della lamina (valore di riferimento) 3 Raggio esterno (R) R = spessore della lamina \u00d7 2 (valore di riferimento) Forma di curvatura a R (curvatura FR) No. Parte standard Valore standard Esempio 1 Tolleranza angolo di curvatura \u00b12,0\u00b0 2 R interno Dimensioni di modellazione (valore di riferimento) 3 R esterno R interno + spessore della lamina (valore di riferimento) Sporgenze dovute alla curvabilit\u00e0 Valore standard Esempio Come mostrato nell&#8217;esempio a [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[240],"tags":[238],"class_list":["post-39940","post","type-post","status-publish","format-standard","hentry","category-shm_conditions-it-c","tag-technical_shm-it"],"views":16,"_links":{"self":[{"href":"https:\/\/de.meviy.misumi-ec.com\/help\/it\/wp-json\/wp\/v2\/posts\/39940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/de.meviy.misumi-ec.com\/help\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/de.meviy.misumi-ec.com\/help\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/de.meviy.misumi-ec.com\/help\/it\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/de.meviy.misumi-ec.com\/help\/it\/wp-json\/wp\/v2\/comments?post=39940"}],"version-history":[{"count":30,"href":"https:\/\/de.meviy.misumi-ec.com\/help\/it\/wp-json\/wp\/v2\/posts\/39940\/revisions"}],"predecessor-version":[{"id":89140,"href":"https:\/\/de.meviy.misumi-ec.com\/help\/it\/wp-json\/wp\/v2\/posts\/39940\/revisions\/89140"}],"wp:attachment":[{"href":"https:\/\/de.meviy.misumi-ec.com\/help\/it\/wp-json\/wp\/v2\/media?parent=39940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/de.meviy.misumi-ec.com\/help\/it\/wp-json\/wp\/v2\/categories?post=39940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/de.meviy.misumi-ec.com\/help\/it\/wp-json\/wp\/v2\/tags?post=39940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}