{"id":18260,"date":"2021-09-05T15:21:46","date_gmt":"2021-09-05T06:21:46","guid":{"rendered":"https:\/\/de.meviy.misumi-ec.com\/info\/?p=18260"},"modified":"2025-05-03T18:32:21","modified_gmt":"2025-05-03T09:32:21","slug":"neue-blechdicke-jetzt-auch-16-mm-dicke-fuer-aluminium-verfuegbar","status":"publish","type":"post","link":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/18260\/","title":{"rendered":"Neue Blechdicke: Jetzt auch 1,6 mm Dicke f\u00fcr Aluminium verf\u00fcgbar"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"18260\" class=\"elementor elementor-18260\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48a613b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48a613b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e060429\" data-id=\"e060429\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a30870 elementor-widget elementor-widget-text-editor\" data-id=\"2a30870\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-family: arial, helvetica, sans-serif; font-size: 12pt; color: #000000;\">Seit dem 14. Mai 2021 ist die Blechdicke &#8222;EN AW\u22125052 equiv.&#8220; mit 1,6 mm bei meviy verf\u00fcgbar.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9147cac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9147cac\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e698c79\" data-id=\"e698c79\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4286e06 elementor-widget elementor-widget-html\" data-id=\"4286e06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div style=\"border: 2px solid #555; border-radius: 10px; padding: 15px; width: 70%; font-size: 12pt;\">\n<p><font style=\"line-height: 1.9;\"><strong>Wird empfohlen, wenn:<\/strong><\/font><\/p>\n<p>&bull; Das Ziel ist, das Gewicht zu reduzieren <span style=\"font-size: 9pt;\">(*Bitte beachten Sie, dass beim Wechsel von Stahl zu Aluminium die Festigkeit des Materials reduziert wird.)<\/span><\/p>\n<p><font style=\"line-height: 1.6;\">&bull; Es schwierig ist, die Teilen mit einer Dicke von 1,6 mm von anderen Firmen zu beziehen<\/font><\/p>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8514acc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8514acc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-068e024\" data-id=\"068e024\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6991bfd elementor-widget elementor-widget-heading\" data-id=\"6991bfd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Material- und Blechdicke<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b1689b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b1689b8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ee32808\" data-id=\"ee32808\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3c551f elementor-widget elementor-widget-html\" data-id=\"a3c551f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<table style=\"width: 100%; border-collapse: collapse; border: 1px solid #8a8a8a; font-size: 12pt; margin-top: 20px;\">\n<tbody>\n<tr>\n<td style=\"text-align: center; background-color: #f2f2f2; border: 1px solid #8a8a8a; width: 20%; padding: 5px;\"><b> Werkstoff:<br>Aluminium<\/b><\/td>\n<td style=\"text-align: center; background-color: #f2f2f2; border: 1px solid #8a8a8a; width: 25%; padding: 5px;\"><strong>Oberfl\u00e4chenbehandlung<\/strong><\/td>\n<td style=\"text-align: center; background-color: #f2f2f2; border: 1px solid #8a8a8a; width: 55%; padding: 5px;\"><strong>Blechdicke (in mm) <span style=\"color: #ff0000; font-size: 10pt;\"><br>(Neu in rot)<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"background-color: #f2f2f2; border: 1px solid #8a8a8a; width: 20.9375%; text-align: center;\" rowspan=\"4\">EN AW\u22125052 equiv.<\/td>\n<td style=\"text-align: center; background-color: #f2f2f2; border: 1px solid #8a8a8a; width: 24.6875%; padding: 5px;\">\u2015<\/td>\n<td style=\"width: 25%; border: 1px solid #8a8a8a; background-color: #d2e8f4; text-align: center;\" rowspan=\"4\">0.8&#160;&#160;&#160;&#160;1.0&#160;&#160;&#160;&#160;1.2&#160;&#160;&#160;&#160;1.5&#160;&#160;&#160;&#160;\n<span style=\"color: red;\"><strong>1.6<\/strong><\/span>&#160;&#160;&#160;&#160;2.0&#160;&#160;&#160;&#160;2.5&#160;&#160;&#160;&#160;3.0&#160;&#160;&#160;4.0&#160;&#160;&#160;&#160;5.0&#160;&#160;&#160;&#160;6.0  \n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 24.6875%; text-align: center; background-color: #f2f2f2; border: 1px solid #8a8a8a; padding: 5px;\">Wei\u00df eloxiert<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 24.6875%; text-align: center; background-color: #f2f2f2; border: 1px solid #8a8a8a; padding: 5px;\">Schwarz eloxiert<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 24.6875%; text-align: center; background-color: #f2f2f2; border: 1px solid #8a8a8a; padding: 5px;\">Schwarz eloxiert (matt)<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cebfea elementor-widget elementor-widget-text-editor\" data-id=\"1cebfea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-family: arial, helvetica, sans-serif; font-size: 12pt; color: #000000;\">Mit der Erg\u00e4nzung von 1,6\u00a0mm hat sich die Blechdicke auf insgesamt 44 Typen erh\u00f6ht. Die Oberfl\u00e4chenbehandlung kann f\u00fcr alle Dicken aus vier Mustern spezifiziert werden.<\/span><\/p><p>\u00a0<\/p><p><span style=\"font-family: arial, helvetica, sans-serif; color: #000000; font-size: 12pt;\">\u00b7 Keine Oberfl\u00e4chenbehandlung: 6 Tage Standardlieferung<\/span><\/p><p><span style=\"font-family: arial, helvetica, sans-serif; color: #000000; font-size: 12pt;\">\u00b7 Wei\u00df\/Schwarz\/Schwarz(matt) eloxiert: 8 Tage Standardlieferung<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fb751a elementor-widget elementor-widget-spacer\" data-id=\"6fb751a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e72932 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e72932\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-92c736d\" data-id=\"92c736d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5e28ba elementor-widget elementor-widget-image\" data-id=\"c5e28ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"505\" src=\"https:\/\/de.meviy.misumi-ec.com\/info\/wp-content\/uploads\/2021\/09\/Blechdicke_Produktbilder.jpg\" class=\"attachment-large size-large wp-image-18424\" alt=\"Blechdicke_Produktbilder\" srcset=\"https:\/\/de.meviy.misumi-ec.com\/info\/wp-content\/uploads\/2021\/09\/Blechdicke_Produktbilder.jpg 768w, https:\/\/de.meviy.misumi-ec.com\/info\/wp-content\/uploads\/2021\/09\/Blechdicke_Produktbilder-300x197.jpg 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3264ea5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3264ea5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ba71ff8\" data-id=\"ba71ff8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ab0674 elementor-widget elementor-widget-text-editor\" data-id=\"2ab0674\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-family: arial, helvetica, sans-serif; color: #000000; font-size: 10pt;\">Von links nach rechts: Blechdicke 0.8\/1.0\/1.2\/1.5\/1.6\/2.0\/2.5\/3.0\/4.0\/5.0\/6.0 mm<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9428509 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9428509\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7bbda43\" data-id=\"7bbda43\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5e6f65 elementor-widget elementor-widget-heading\" data-id=\"c5e6f65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bearbeitungsbereich<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-860cccf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"860cccf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9820ba4\" data-id=\"9820ba4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-efd3a1e elementor-widget elementor-widget-html\" data-id=\"efd3a1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<table style=\"width: 100%; border-collapse: collapse; border: 1px solid #8a8a8a; font-size: 12pt; margin-top: 20px;\">\n<tbody>\n<tr>\n<td style=\"width: 20%; text-align: center; background-color: #f2f2f2; border: 1px solid #8a8a8a;\" rowspan=\"2\"><strong>Werkstoff:<\/strong><br>\n<strong>Aluminium<\/strong><\/td>\n<td style=\"width: 15%; text-align: center; background-color: #f2f2f2; border: 1px solid #8a8a8a;\" rowspan=\"2\"><strong>Oberfl\u00e4chenbehandlung<\/strong><\/td>\n<td style=\"width: 40%; text-align: center; background-color: #f2f2f2; border: 1px solid #8a8a8a; padding: 5px;\" colspan=\"2\"><strong>Au\u00dfenabmessungen<\/strong><br>\n<strong>(L\u00e4nge, Breite, H\u00f6he)*<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 20%; text-align: center; background-color: #f2f2f2; border: 1px solid #8a8a8a; padding: 5px;\"><strong>Blechdicke<\/strong><br>\n<strong>\u2264 2.0 mm<\/strong><\/td>\n<td style=\"width: 20%; text-align: center; background-color: #f2f2f2; border: 1px solid #8a8a8a;\"><strong>Blechdicke<\/strong><br>\n<strong>> 2.0 mm<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; background-color: #f2f2f2; border: 1px solid #8a8a8a; width: 20%; vertical-align: inherit;\" rowspan=\"4\"><font style=\"vertical-align: inherit;\">EN AW\u22125052 equiv.<\/font><\/td>\n<td style=\"width: 15%; text-align: center; background-color: #f2f2f2; border: 1px solid #8a8a8a; padding: 5px;\">\u2015<\/td>\n<td style=\"text-align: center; background-color: #ddebf7; border: 1px solid #8a8a8a; width: 20%;\">5 - 1200<\/td>\n<td style=\"text-align: center; background-color: #ddebf7; border: 1px solid #8a8a8a; width: 20%;\">10 - 1200<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 15%; text-align: center; background-color: #f2f2f2; border: 1px solid #8a8a8a; padding: 5px;\"><span style=\"font-size: 12pt;\">Wei\u00df eloxiert<\/span><\/td>\n<td style=\"text-align: center; background-color: #ddebf7; border: 1px solid #8a8a8a; width: 20%;\" rowspan=\"2\">5 - 1200**<br><\/td>\n<td style=\"text-align: center; background-color: #ddebf7; border: 1px solid #8a8a8a; width: 20%;\" rowspan=\"2\">10 - 1200**<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 15%; text-align: center; background-color: #f2f2f2; border: 1px solid #8a8a8a; padding: 5px;\"><span style=\"font-size: 12pt;\">Schwarz eloxiert<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 15%; text-align: center; background-color: #f2f2f2; border: 1px solid #8a8a8a; padding: 5px;\"><span style=\"font-size: 12pt;\">Schwarz eloxiert (matt)<\/span><\/td>\n<td style=\"text-align: center; background-color: #ddebf7; border: 1px solid #8a8a8a; width: 20%;\">5 - 1100**<\/td>\n<td style=\"text-align: center; background-color: #ddebf7; border: 1px solid #8a8a8a; width: 20%;\">10 - 1100**<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b11efd elementor-widget elementor-widget-text-editor\" data-id=\"9b11efd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-family: arial, helvetica, sans-serif; color: #000000; font-size: 10pt;\">* Die maximalen und minimalen Abmessungen werden durch die Form der Biegung begrenzt<\/span><\/p><p><span style=\"font-family: arial, helvetica, sans-serif; color: #000000; font-size: 10pt;\">** Die maximalen L\u00e4ngen- und Breitenabmessungen k\u00f6nnen je nach Oberfl\u00e4chenbehandlung variieren.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0a86f4e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0a86f4e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ba6d30\" data-id=\"6ba6d30\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b90b5c6 elementor-widget elementor-widget-spacer\" data-id=\"b90b5c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43d0bbd elementor-widget elementor-widget-html\" data-id=\"43d0bbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<table style=\"width: 100%; border-collapse: collapse; border: 1px solid #8a8a8a; font-size: 12pt;\">\n<tbody>\n<tr>\n<td style=\"width: 20%; text-align: center; background-color: #f2f2f2; border: 1px solid #8a8a8a; padding: 5px;\" rowspan=\"2\"><b>\nMaximale Gr\u00f6\u00dfen f\u00fcr jede Oberfl\u00e4chenbehandlung<\/b><\/td>\n<td style=\"text-align: center; background-color: #f2f2f2; border: 1px solid #8a8a8a; width: 59.8438%; padding: 5px;\" colspan=\"3\"><strong>Au\u00dfenabmessungen<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; background-color: #f2f2f2; border: 1px solid #8a8a8a; padding: 5px; width: 19.8438%;\"><strong>L\u00e4nge<\/strong><\/td>\n<td style=\"width: 20%; text-align: center; background-color: #f2f2f2; border: 1px solid #8a8a8a; padding: 5px;\"><b>Breite<\/b><\/td>\n<td style=\"width: 20%; text-align: center; background-color: #f2f2f2; border: 1px solid #8a8a8a; padding: 5px;\"><strong>H\u00f6he<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 20%; text-align: center; background-color: #f2f2f2; border: 1px solid #8a8a8a; padding: 5px;\">Wei\u00df eloxiert<\/td>\n<td style=\"width: 19.8438%; text-align: center; border: 1px solid #8a8a8a; background-color: #ddebf7;\" rowspan=\"2\">1200<\/td>\n<td style=\"text-align: center; background-color: #ddebf7; border: 1px solid #8a8a8a; width: 20%;\" rowspan=\"2\">600<\/td>\n<td style=\"text-align: center; background-color: #ddebf7; border: 1px solid #8a8a8a; width: 20%;\" rowspan=\"2\">400<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 20%; text-align: center; background-color: #f2f2f2; border: 1px solid #8a8a8a; padding: 5px;\">Schwarz eloxiert<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 20%; text-align: center; background-color: #f2f2f2; border: 1px solid #8a8a8a; padding: 5px;\">Schwarz eloxiert (matt)<\/td>\n<td style=\"width: 19.8438%; text-align: center; border: 1px solid #8a8a8a; background-color: #ddebf7;\">1100<\/td>\n<td style=\"text-align: center; background-color: #ddebf7; border: 1px solid #8a8a8a; width: 20%;\">800<\/td>\n<td style=\"text-align: center; background-color: #ddebf7; border: 1px solid #8a8a8a; width: 20%;\">400<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b1562c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5b1562c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dfed0df\" data-id=\"dfed0df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b33cea6 elementor-widget elementor-widget-heading\" data-id=\"b33cea6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Produktionsbeispiel 1<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3605aeb elementor-widget elementor-widget-image\" data-id=\"3605aeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"505\" src=\"https:\/\/de.meviy.misumi-ec.com\/info\/wp-content\/uploads\/2021\/09\/Blechdicke_Produktionsbeispiel.jpg\" class=\"attachment-medium_large size-medium_large wp-image-18428\" alt=\"Blechdicke_Produktionsbeispiel\" srcset=\"https:\/\/de.meviy.misumi-ec.com\/info\/wp-content\/uploads\/2021\/09\/Blechdicke_Produktionsbeispiel.jpg 768w, https:\/\/de.meviy.misumi-ec.com\/info\/wp-content\/uploads\/2021\/09\/Blechdicke_Produktionsbeispiel-300x197.jpg 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11cf192 elementor-widget elementor-widget-html\" data-id=\"11cf192\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<table style=\"width: 70%; border-collapse: collapse; border-style: none; font-size: 12pt;\">\n<tbody>\n<tr>\n<td style=\"width: 90%; border-style: none;\">\n<ul>\n<li style=\"padding: 5px\">&bull; Werkstoff: EN AW\u22125052 equiv.<\/li>\n<li style=\"padding: 5px\">&bull; Oberfl\u00e4chenbehandlung: Oben links - Schwarz eloxiert (matt), Oben rechts - Wei\u00df eloxiert, Unten links - Schwarz eloxiert, Unten rechts - Keine Oberfl\u00e4chenbehandlung<\/li>\n<li style=\"padding: 5px\">&bull; Gr\u00f6\u00dfe: 100\u00d770\u00d71.6 mm<\/li>\n<li style=\"padding: 5px\">&bull; Blechdicke: 1.6 mm<\/li>\n<li style=\"padding: 5px\">&bull; Referenzpreis: Oben links - 32.30\u20ac, oben rechts- 32.20\u20ac, unten links- 32.20\u20ac, unten rechts - 28\u20ac<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e4be21a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e4be21a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6bc6455\" data-id=\"6bc6455\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-549ad9b elementor-widget elementor-widget-heading\" data-id=\"549ad9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Produktionsbeispiel 2<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b0ac88 elementor-widget elementor-widget-image\" data-id=\"7b0ac88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"506\" src=\"https:\/\/de.meviy.misumi-ec.com\/info\/wp-content\/uploads\/2021\/09\/Blechdicke_Produktionsbeispiel1.jpg\" class=\"attachment-medium_large size-medium_large wp-image-18426\" alt=\"Blechdicke_Produktionsbeispiel1\" srcset=\"https:\/\/de.meviy.misumi-ec.com\/info\/wp-content\/uploads\/2021\/09\/Blechdicke_Produktionsbeispiel1.jpg 768w, https:\/\/de.meviy.misumi-ec.com\/info\/wp-content\/uploads\/2021\/09\/Blechdicke_Produktionsbeispiel1-300x198.jpg 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ce65132 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ce65132\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d893006\" data-id=\"d893006\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f4dd4a elementor-widget elementor-widget-html\" data-id=\"7f4dd4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<table style=\"width: 70%; border-collapse: collapse; border-style: none; font-size: 12pt\">\n<tbody>\n<tr>\n<td style=\"width: 100%; border-style: none;\">\n<ul>\n<li style=\"padding: 5px\">&bull; Werkstoff: EN AW\u22125052 equiv.<\/li>\n<li style=\"padding: 5px\">&bull; Oberfl\u00e4chenbehandlung: (Von links nach rechts) Keine Oberfl\u00e4chenbehandlung\/ Schwarz eloxiert\/ Wei\u00df eloxiert\/ Schwarz eloxiert (matt)<\/li>\n<li style=\"padding: 5px\">&bull; Gr\u00f6\u00dfe: 120\u00d760\u00d7113 mm (ersten drei links) \/ 91\u00d760\u00d7103 mm (rechts)<\/li>\n<li style=\"padding: 5px\">&bull; Bleckdicke: 1.6 mm<\/li>\n<li style=\"padding: 5px\">&bull; Referenzpreis: 35.30\u20ac, 40.30\u20ac, 40.30\u20ac, 45.20\u20ac (von links nach rechts)<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-708cf4c elementor-widget elementor-widget-spacer\" data-id=\"708cf4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84d7225 elementor-widget elementor-widget-text-editor\" data-id=\"84d7225\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><span style=\"font-family: arial, helvetica, sans-serif; font-size: 12pt; color: #000000;\">meviy bietet eine breite Palette an Blechdicken mit automatischem Angebot und schneller Lieferung!<\/span><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bd6f434 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bd6f434\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-095abe2\" data-id=\"095abe2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d20b54c elementor-widget elementor-widget-heading\" data-id=\"d20b54c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Bleche - meviy FA Handbuch<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-508d251 elementor-widget elementor-widget-html\" data-id=\"508d251\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<table style=\"width: 50%; border-collapse: collapse; border-style: none; font-size: 12pt;\">\r\n<tbody>\r\n<tr>\r\n<td style=\"width: 90%; border-style: none;\">\r\n<ul>\r\n<li style=\"padding: 5px\"><a href=\"https:\/\/de.meviy.misumi-ec.com\/help\/de\/technical_info-de\/shm_shape-material-de\/\">&bull; Anwendbare Teile\/Materialien<\/a><\/li>\r\n<li style=\"padding: 5px\"><a href=\"https:\/\/de.meviy.misumi-ec.com\/help\/de\/technical_info-de\/shm_guideline-de\/\">&bull; Designrichtlinien<\/a><\/li>\r\n<li style=\"padding: 5px\"><a href=\"https:\/\/de.meviy.misumi-ec.com\/help\/de\/technical_info-de\/shm_conditions-de\/\">&bull; Genauigkeit und Verarbeitungsbedingungen<\/a><\/li>\r\n<\/ul>\r\n<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e63f26c elementor-widget elementor-widget-heading\" data-id=\"e63f26c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Haben Sie weitere Fragen?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b96a7d elementor-widget elementor-widget-text-editor\" data-id=\"5b96a7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-family: arial, helvetica, sans-serif; font-size: 12pt; color: #000000;\">Unser meviy Support Team hilft Ihnen gerne weiter: <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"mailto:meviy-eu@misumi-europe.com\">meviy-eu@misumi-europe.com<\/a><\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Seit dem 14. Mai 2021 ist die Blechdicke &#8222;EN AW\u22125052 equiv.&#8220; mit 1,6 mm bei meviy verf\u00fcgbar. Wird empfohlen, wenn: \u2022 Das Ziel ist, das Gewicht zu reduzieren (*Bitte beachten Sie, dass beim Wechsel von Stahl zu Aluminium die Festigkeit des Materials reduziert wird.) \u2022 Es schwierig ist, die Teilen mit einer Dicke von 1,6 mm von anderen Firmen zu beziehen Material- und Blechdicke Werkstoff: Aluminium Oberfl\u00e4chenbehandlung Blechdicke (in mm) (Neu in rot) EN AW\u22125052 equiv. \u2015 0.8\u00a0\u00a0\u00a0\u00a01.0\u00a0\u00a0\u00a0\u00a01.2\u00a0\u00a0\u00a0\u00a01.5 1.6\u00a0\u00a0\u00a0\u00a02.0\u00a0\u00a0\u00a0\u00a02.5\u00a0\u00a0\u00a0\u00a03.0\u00a0\u00a0\u00a04.0\u00a0\u00a0\u00a0\u00a05.0\u00a0\u00a0\u00a0\u00a06.0 Wei\u00df eloxiert Schwarz eloxiert Schwarz eloxiert (matt) Mit der Erg\u00e4nzung von 1,6\u00a0mm hat sich die Blechdicke auf insgesamt 44 Typen erh\u00f6ht. Die Oberfl\u00e4chenbehandlung kann f\u00fcr alle Dicken aus vier Mustern spezifiziert [&hellip;]<\/p>\n","protected":false},"author":51,"featured_media":25529,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[208],"tags":[],"class_list":["post-18260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-service-release-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neue Blechdicke: Jetzt auch 1,6 mm Dicke f\u00fcr Aluminium verf\u00fcgbar | meviy-Gebrauchsanweisungen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/18260\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neue Blechdicke: Jetzt auch 1,6 mm Dicke f\u00fcr Aluminium verf\u00fcgbar | meviy-Gebrauchsanweisungen\" \/>\n<meta property=\"og:description\" content=\"Seit dem 14. Mai 2021 ist die Blechdicke &#8222;EN AW\u22125052 equiv.&#8220; mit 1,6 mm bei meviy verf\u00fcgbar. Wird empfohlen, wenn: \u2022 Das Ziel ist, das Gewicht zu reduzieren (*Bitte beachten Sie, dass beim Wechsel von Stahl zu Aluminium die Festigkeit des Materials reduziert wird.) \u2022 Es schwierig ist, die Teilen mit einer Dicke von 1,6 mm von anderen Firmen zu beziehen Material- und Blechdicke Werkstoff: Aluminium Oberfl\u00e4chenbehandlung Blechdicke (in mm) (Neu in rot) EN AW\u22125052 equiv. \u2015 0.8\u00a0\u00a0\u00a0\u00a01.0\u00a0\u00a0\u00a0\u00a01.2\u00a0\u00a0\u00a0\u00a01.5 1.6\u00a0\u00a0\u00a0\u00a02.0\u00a0\u00a0\u00a0\u00a02.5\u00a0\u00a0\u00a0\u00a03.0\u00a0\u00a0\u00a04.0\u00a0\u00a0\u00a0\u00a05.0\u00a0\u00a0\u00a0\u00a06.0 Wei\u00df eloxiert Schwarz eloxiert Schwarz eloxiert (matt) Mit der Erg\u00e4nzung von 1,6\u00a0mm hat sich die Blechdicke auf insgesamt 44 Typen erh\u00f6ht. Die Oberfl\u00e4chenbehandlung kann f\u00fcr alle Dicken aus vier Mustern spezifiziert [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/18260\/\" \/>\n<meta property=\"og:site_name\" content=\"meviy-Gebrauchsanweisungen\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-05T06:21:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-03T09:32:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/de.meviy.misumi-ec.com\/info\/wp-content\/uploads\/2021\/08\/New-plate-thickness.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"505\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Viola Hoppe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viola Hoppe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/service-release-de\\\/18260\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/service-release-de\\\/18260\\\/\"},\"author\":{\"name\":\"Viola Hoppe\",\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/#\\\/schema\\\/person\\\/e95b397e6beb97edb528ace15efa8c5c\"},\"headline\":\"Neue Blechdicke: Jetzt auch 1,6 mm Dicke f\u00fcr Aluminium verf\u00fcgbar\",\"datePublished\":\"2021-09-05T06:21:46+00:00\",\"dateModified\":\"2025-05-03T09:32:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/service-release-de\\\/18260\\\/\"},\"wordCount\":337,\"publisher\":{\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/service-release-de\\\/18260\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/New-plate-thickness.jpg\",\"articleSection\":[\"Serviceaktualisierungen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/service-release-de\\\/18260\\\/\",\"url\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/service-release-de\\\/18260\\\/\",\"name\":\"Neue Blechdicke: Jetzt auch 1,6 mm Dicke f\u00fcr Aluminium verf\u00fcgbar | meviy-Gebrauchsanweisungen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/service-release-de\\\/18260\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/service-release-de\\\/18260\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/New-plate-thickness.jpg\",\"datePublished\":\"2021-09-05T06:21:46+00:00\",\"dateModified\":\"2025-05-03T09:32:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/service-release-de\\\/18260\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/service-release-de\\\/18260\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/service-release-de\\\/18260\\\/#primaryimage\",\"url\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/New-plate-thickness.jpg\",\"contentUrl\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/New-plate-thickness.jpg\",\"width\":768,\"height\":505},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/service-release-de\\\/18260\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"BLOG\",\"item\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neue Blechdicke: Jetzt auch 1,6 mm Dicke f\u00fcr Aluminium verf\u00fcgbar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/\",\"name\":\"meviy Europe - Blog - MISUMI\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/#organization\",\"name\":\"meviy Europe - MISUMI\",\"url\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/A01-b_b4-1_jpeg.jpg\",\"contentUrl\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/A01-b_b4-1_jpeg.jpg\",\"width\":260,\"height\":70,\"caption\":\"meviy Europe - MISUMI\"},\"image\":{\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/#\\\/schema\\\/person\\\/e95b397e6beb97edb528ace15efa8c5c\",\"name\":\"Viola Hoppe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98cff4d18d14ca33967ce56235d78518c1ff666730e348a8ca0540f8066ff028?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98cff4d18d14ca33967ce56235d78518c1ff666730e348a8ca0540f8066ff028?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98cff4d18d14ca33967ce56235d78518c1ff666730e348a8ca0540f8066ff028?s=96&d=mm&r=g\",\"caption\":\"Viola Hoppe\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neue Blechdicke: Jetzt auch 1,6 mm Dicke f\u00fcr Aluminium verf\u00fcgbar | meviy-Gebrauchsanweisungen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/18260\/","og_locale":"de_DE","og_type":"article","og_title":"Neue Blechdicke: Jetzt auch 1,6 mm Dicke f\u00fcr Aluminium verf\u00fcgbar | meviy-Gebrauchsanweisungen","og_description":"Seit dem 14. Mai 2021 ist die Blechdicke &#8222;EN AW\u22125052 equiv.&#8220; mit 1,6 mm bei meviy verf\u00fcgbar. Wird empfohlen, wenn: \u2022 Das Ziel ist, das Gewicht zu reduzieren (*Bitte beachten Sie, dass beim Wechsel von Stahl zu Aluminium die Festigkeit des Materials reduziert wird.) \u2022 Es schwierig ist, die Teilen mit einer Dicke von 1,6 mm von anderen Firmen zu beziehen Material- und Blechdicke Werkstoff: Aluminium Oberfl\u00e4chenbehandlung Blechdicke (in mm) (Neu in rot) EN AW\u22125052 equiv. \u2015 0.8\u00a0\u00a0\u00a0\u00a01.0\u00a0\u00a0\u00a0\u00a01.2\u00a0\u00a0\u00a0\u00a01.5 1.6\u00a0\u00a0\u00a0\u00a02.0\u00a0\u00a0\u00a0\u00a02.5\u00a0\u00a0\u00a0\u00a03.0\u00a0\u00a0\u00a04.0\u00a0\u00a0\u00a0\u00a05.0\u00a0\u00a0\u00a0\u00a06.0 Wei\u00df eloxiert Schwarz eloxiert Schwarz eloxiert (matt) Mit der Erg\u00e4nzung von 1,6\u00a0mm hat sich die Blechdicke auf insgesamt 44 Typen erh\u00f6ht. Die Oberfl\u00e4chenbehandlung kann f\u00fcr alle Dicken aus vier Mustern spezifiziert [&hellip;]","og_url":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/18260\/","og_site_name":"meviy-Gebrauchsanweisungen","article_published_time":"2021-09-05T06:21:46+00:00","article_modified_time":"2025-05-03T09:32:21+00:00","og_image":[{"width":768,"height":505,"url":"https:\/\/de.meviy.misumi-ec.com\/info\/wp-content\/uploads\/2021\/08\/New-plate-thickness.jpg","type":"image\/jpeg"}],"author":"Viola Hoppe","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Viola Hoppe","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/18260\/#article","isPartOf":{"@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/18260\/"},"author":{"name":"Viola Hoppe","@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/#\/schema\/person\/e95b397e6beb97edb528ace15efa8c5c"},"headline":"Neue Blechdicke: Jetzt auch 1,6 mm Dicke f\u00fcr Aluminium verf\u00fcgbar","datePublished":"2021-09-05T06:21:46+00:00","dateModified":"2025-05-03T09:32:21+00:00","mainEntityOfPage":{"@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/18260\/"},"wordCount":337,"publisher":{"@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/#organization"},"image":{"@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/18260\/#primaryimage"},"thumbnailUrl":"https:\/\/de.meviy.misumi-ec.com\/info\/wp-content\/uploads\/2021\/08\/New-plate-thickness.jpg","articleSection":["Serviceaktualisierungen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/18260\/","url":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/18260\/","name":"Neue Blechdicke: Jetzt auch 1,6 mm Dicke f\u00fcr Aluminium verf\u00fcgbar | meviy-Gebrauchsanweisungen","isPartOf":{"@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/18260\/#primaryimage"},"image":{"@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/18260\/#primaryimage"},"thumbnailUrl":"https:\/\/de.meviy.misumi-ec.com\/info\/wp-content\/uploads\/2021\/08\/New-plate-thickness.jpg","datePublished":"2021-09-05T06:21:46+00:00","dateModified":"2025-05-03T09:32:21+00:00","breadcrumb":{"@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/18260\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/18260\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/18260\/#primaryimage","url":"https:\/\/de.meviy.misumi-ec.com\/info\/wp-content\/uploads\/2021\/08\/New-plate-thickness.jpg","contentUrl":"https:\/\/de.meviy.misumi-ec.com\/info\/wp-content\/uploads\/2021\/08\/New-plate-thickness.jpg","width":768,"height":505},{"@type":"BreadcrumbList","@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/18260\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"BLOG","item":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/"},{"@type":"ListItem","position":2,"name":"Neue Blechdicke: Jetzt auch 1,6 mm Dicke f\u00fcr Aluminium verf\u00fcgbar"}]},{"@type":"WebSite","@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/#website","url":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/","name":"meviy Europe - Blog - MISUMI","description":"","publisher":{"@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/#organization","name":"meviy Europe - MISUMI","url":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/#\/schema\/logo\/image\/","url":"https:\/\/de.meviy.misumi-ec.com\/info\/wp-content\/uploads\/2019\/05\/A01-b_b4-1_jpeg.jpg","contentUrl":"https:\/\/de.meviy.misumi-ec.com\/info\/wp-content\/uploads\/2019\/05\/A01-b_b4-1_jpeg.jpg","width":260,"height":70,"caption":"meviy Europe - MISUMI"},"image":{"@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/#\/schema\/person\/e95b397e6beb97edb528ace15efa8c5c","name":"Viola Hoppe","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/98cff4d18d14ca33967ce56235d78518c1ff666730e348a8ca0540f8066ff028?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/98cff4d18d14ca33967ce56235d78518c1ff666730e348a8ca0540f8066ff028?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98cff4d18d14ca33967ce56235d78518c1ff666730e348a8ca0540f8066ff028?s=96&d=mm&r=g","caption":"Viola Hoppe"}}]}},"views":354,"_links":{"self":[{"href":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/wp-json\/wp\/v2\/posts\/18260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/wp-json\/wp\/v2\/comments?post=18260"}],"version-history":[{"count":4,"href":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/wp-json\/wp\/v2\/posts\/18260\/revisions"}],"predecessor-version":[{"id":18582,"href":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/wp-json\/wp\/v2\/posts\/18260\/revisions\/18582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/wp-json\/wp\/v2\/media\/25529"}],"wp:attachment":[{"href":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/wp-json\/wp\/v2\/media?parent=18260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/wp-json\/wp\/v2\/categories?post=18260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/wp-json\/wp\/v2\/tags?post=18260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}