{"id":19649,"date":"2021-12-23T17:28:00","date_gmt":"2021-12-23T08:28:00","guid":{"rendered":"https:\/\/de.meviy.misumi-ec.com\/info\/?p=19649"},"modified":"2021-12-23T17:28:00","modified_gmt":"2021-12-23T08:28:00","slug":"mitteilung-zur-behebung-der-apache-log4j-sicherheitslucke-cve-2021-44228","status":"publish","type":"post","link":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/19649\/","title":{"rendered":"Mitteilung zur Behebung der Apache Log4j Sicherheitsl\u00fccke (CVE-2021-44228)"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"19649\" class=\"elementor elementor-19649 elementor-19643\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fdcc8af elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fdcc8af\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9da6f01\" data-id=\"9da6f01\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b22fc9 elementor-widget elementor-widget-text-editor\" data-id=\"2b22fc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-family: arial, helvetica, sans-serif; font-size: 12pt; color: #000000;\">Wir m\u00f6chten Sie \u00fcber den Status unserer Untersuchung und Reaktion auf die Sicherheitsl\u00fccke von Apache Log4j* informieren, die am 9. Dezember 2021 ver\u00f6ffentlicht wurde:<\/span><\/p><p>\u00a0<\/p><p><strong><span style=\"font-family: arial, helvetica, sans-serif; font-size: 12pt; color: #000000;\">F\u00fcr den Service meviy wurden alle Schwachstellen im Bezug auf die Log4j-Sicherheitsl\u00fccke behoben!<\/span><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ff13e9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ff13e9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a4d8886\" data-id=\"a4d8886\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf43920 elementor-widget elementor-widget-html\" data-id=\"cf43920\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<table style=\"width: 70%; border-collapse: collapse; border-style: none; font-size: 12pt;\">\n<tbody>\n    <tr>\n        <td>Informationen zur Untersuchung und Gegenma\u00dfnahmen:\n        <\/td>\n    <\/tr>\n<tr>\n<td style=\"border-style: none;\">\n<ul>\n<li style=\"padding: 15px 5px 5px 5px\">&bull; Die meviy-Serveranwendung verwendet die betroffene Bibliothek nicht<\/li>\n<li style=\"padding: 5px\">&bull; Als Gegenma\u00dfnahme wurden am 13. Dezember WAF-Regeln zum Blockieren von Angriffen auf die log4j-Schwachstelle angewendet.<\/li>\n<li style=\"padding: 5px\">&bull; Einige Middleware, die keine externe Kommunikation ausf\u00fchren, verwenden log4j. Am 21. Dezember wurde ein Update f\u00fcr die entsprechenden Middleware eingespielt<\/li>\n\t\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d63b132 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d63b132\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1349968\" data-id=\"1349968\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef19185 elementor-widget elementor-widget-text-editor\" data-id=\"ef19185\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-family: arial, helvetica, sans-serif; color: #000000; font-size: 12pt;\">Wir werden weiterhin Informationen \u00fcber diese Schwachstelle sammeln und bei Bedarf Gegenma\u00dfnahmen ergreifen.<\/span><\/p><p><span style=\"font-family: arial, helvetica, sans-serif; font-size: 10pt; color: #000000;\">\u00a0<\/span><\/p><p><span style=\"font-family: arial, helvetica, sans-serif; font-size: 10pt; color: #000000;\">*Apache Log4j ist eine weit verbreitete Bibliothek f\u00fcr Java-basierte Systeme. Die am 9. Dezember 2021 bekannt gewordene Schwachstelle k\u00f6nnte, wenn sie ausgenutzt wird, einem Dritten die M\u00f6glichkeit geben, beliebigen Code auszuf\u00fchren, indem manipulierte Daten gesendet werden.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Wir m\u00f6chten Sie \u00fcber den Status unserer Untersuchung und Reaktion auf die Sicherheitsl\u00fccke von Apache Log4j* informieren, die am 9. Dezember 2021 ver\u00f6ffentlicht wurde: F\u00fcr den Service meviy wurden alle Schwachstellen im Bezug auf die Log4j-Sicherheitsl\u00fccke behoben! Informationen zur Untersuchung und Gegenma\u00dfnahmen: \u2022 Die meviy-Serveranwendung verwendet die betroffene Bibliothek nicht \u2022 Als Gegenma\u00dfnahme wurden am 13. Dezember WAF-Regeln zum Blockieren von Angriffen auf die log4j-Schwachstelle angewendet. \u2022 Einige Middleware, die keine externe Kommunikation ausf\u00fchren, verwenden log4j. Am 21. Dezember wurde ein Update f\u00fcr die entsprechenden Middleware eingespielt Wir werden weiterhin Informationen \u00fcber diese Schwachstelle sammeln und bei Bedarf Gegenma\u00dfnahmen ergreifen. *Apache Log4j ist eine weit verbreitete Bibliothek f\u00fcr Java-basierte Systeme. [&hellip;]<\/p>\n","protected":false},"author":51,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[208],"tags":[],"class_list":["post-19649","post","type-post","status-publish","format-standard","hentry","category-service-release-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mitteilung zur Behebung der Apache Log4j Sicherheitsl\u00fccke (CVE-2021-44228) | meviy-Gebrauchsanweisungen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/19649\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mitteilung zur Behebung der Apache Log4j Sicherheitsl\u00fccke (CVE-2021-44228) | meviy-Gebrauchsanweisungen\" \/>\n<meta property=\"og:description\" content=\"Wir m\u00f6chten Sie \u00fcber den Status unserer Untersuchung und Reaktion auf die Sicherheitsl\u00fccke von Apache Log4j* informieren, die am 9. Dezember 2021 ver\u00f6ffentlicht wurde: F\u00fcr den Service meviy wurden alle Schwachstellen im Bezug auf die Log4j-Sicherheitsl\u00fccke behoben! Informationen zur Untersuchung und Gegenma\u00dfnahmen: \u2022 Die meviy-Serveranwendung verwendet die betroffene Bibliothek nicht \u2022 Als Gegenma\u00dfnahme wurden am 13. Dezember WAF-Regeln zum Blockieren von Angriffen auf die log4j-Schwachstelle angewendet. \u2022 Einige Middleware, die keine externe Kommunikation ausf\u00fchren, verwenden log4j. Am 21. Dezember wurde ein Update f\u00fcr die entsprechenden Middleware eingespielt Wir werden weiterhin Informationen \u00fcber diese Schwachstelle sammeln und bei Bedarf Gegenma\u00dfnahmen ergreifen. *Apache Log4j ist eine weit verbreitete Bibliothek f\u00fcr Java-basierte Systeme. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/19649\/\" \/>\n<meta property=\"og:site_name\" content=\"meviy-Gebrauchsanweisungen\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-23T08:28:00+00:00\" \/>\n<meta name=\"author\" content=\"Viola Hoppe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viola Hoppe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/service-release-de\\\/19649\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/service-release-de\\\/19649\\\/\"},\"author\":{\"name\":\"Viola Hoppe\",\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/#\\\/schema\\\/person\\\/e95b397e6beb97edb528ace15efa8c5c\"},\"headline\":\"Mitteilung zur Behebung der Apache Log4j Sicherheitsl\u00fccke (CVE-2021-44228)\",\"datePublished\":\"2021-12-23T08:28:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/service-release-de\\\/19649\\\/\"},\"wordCount\":157,\"publisher\":{\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/#organization\"},\"articleSection\":[\"Serviceaktualisierungen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/service-release-de\\\/19649\\\/\",\"url\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/service-release-de\\\/19649\\\/\",\"name\":\"Mitteilung zur Behebung der Apache Log4j Sicherheitsl\u00fccke (CVE-2021-44228) | meviy-Gebrauchsanweisungen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/#website\"},\"datePublished\":\"2021-12-23T08:28:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/service-release-de\\\/19649\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/service-release-de\\\/19649\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/service-release-de\\\/19649\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"BLOG\",\"item\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mitteilung zur Behebung der Apache Log4j Sicherheitsl\u00fccke (CVE-2021-44228)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/\",\"name\":\"meviy Europe - Blog - MISUMI\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/#organization\",\"name\":\"meviy Europe - MISUMI\",\"url\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/A01-b_b4-1_jpeg.jpg\",\"contentUrl\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/A01-b_b4-1_jpeg.jpg\",\"width\":260,\"height\":70,\"caption\":\"meviy Europe - MISUMI\"},\"image\":{\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/de.meviy.misumi-ec.com\\\/info\\\/de\\\/#\\\/schema\\\/person\\\/e95b397e6beb97edb528ace15efa8c5c\",\"name\":\"Viola Hoppe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98cff4d18d14ca33967ce56235d78518c1ff666730e348a8ca0540f8066ff028?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98cff4d18d14ca33967ce56235d78518c1ff666730e348a8ca0540f8066ff028?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98cff4d18d14ca33967ce56235d78518c1ff666730e348a8ca0540f8066ff028?s=96&d=mm&r=g\",\"caption\":\"Viola Hoppe\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mitteilung zur Behebung der Apache Log4j Sicherheitsl\u00fccke (CVE-2021-44228) | meviy-Gebrauchsanweisungen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/19649\/","og_locale":"de_DE","og_type":"article","og_title":"Mitteilung zur Behebung der Apache Log4j Sicherheitsl\u00fccke (CVE-2021-44228) | meviy-Gebrauchsanweisungen","og_description":"Wir m\u00f6chten Sie \u00fcber den Status unserer Untersuchung und Reaktion auf die Sicherheitsl\u00fccke von Apache Log4j* informieren, die am 9. Dezember 2021 ver\u00f6ffentlicht wurde: F\u00fcr den Service meviy wurden alle Schwachstellen im Bezug auf die Log4j-Sicherheitsl\u00fccke behoben! Informationen zur Untersuchung und Gegenma\u00dfnahmen: \u2022 Die meviy-Serveranwendung verwendet die betroffene Bibliothek nicht \u2022 Als Gegenma\u00dfnahme wurden am 13. Dezember WAF-Regeln zum Blockieren von Angriffen auf die log4j-Schwachstelle angewendet. \u2022 Einige Middleware, die keine externe Kommunikation ausf\u00fchren, verwenden log4j. Am 21. Dezember wurde ein Update f\u00fcr die entsprechenden Middleware eingespielt Wir werden weiterhin Informationen \u00fcber diese Schwachstelle sammeln und bei Bedarf Gegenma\u00dfnahmen ergreifen. *Apache Log4j ist eine weit verbreitete Bibliothek f\u00fcr Java-basierte Systeme. [&hellip;]","og_url":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/19649\/","og_site_name":"meviy-Gebrauchsanweisungen","article_published_time":"2021-12-23T08:28:00+00:00","author":"Viola Hoppe","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Viola Hoppe","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/19649\/#article","isPartOf":{"@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/19649\/"},"author":{"name":"Viola Hoppe","@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/#\/schema\/person\/e95b397e6beb97edb528ace15efa8c5c"},"headline":"Mitteilung zur Behebung der Apache Log4j Sicherheitsl\u00fccke (CVE-2021-44228)","datePublished":"2021-12-23T08:28:00+00:00","mainEntityOfPage":{"@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/19649\/"},"wordCount":157,"publisher":{"@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/#organization"},"articleSection":["Serviceaktualisierungen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/19649\/","url":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/19649\/","name":"Mitteilung zur Behebung der Apache Log4j Sicherheitsl\u00fccke (CVE-2021-44228) | meviy-Gebrauchsanweisungen","isPartOf":{"@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/#website"},"datePublished":"2021-12-23T08:28:00+00:00","breadcrumb":{"@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/19649\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/19649\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/service-release-de\/19649\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"BLOG","item":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/"},{"@type":"ListItem","position":2,"name":"Mitteilung zur Behebung der Apache Log4j Sicherheitsl\u00fccke (CVE-2021-44228)"}]},{"@type":"WebSite","@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/#website","url":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/","name":"meviy Europe - Blog - MISUMI","description":"","publisher":{"@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/#organization","name":"meviy Europe - MISUMI","url":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/#\/schema\/logo\/image\/","url":"https:\/\/de.meviy.misumi-ec.com\/info\/wp-content\/uploads\/2019\/05\/A01-b_b4-1_jpeg.jpg","contentUrl":"https:\/\/de.meviy.misumi-ec.com\/info\/wp-content\/uploads\/2019\/05\/A01-b_b4-1_jpeg.jpg","width":260,"height":70,"caption":"meviy Europe - MISUMI"},"image":{"@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/#\/schema\/person\/e95b397e6beb97edb528ace15efa8c5c","name":"Viola Hoppe","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/98cff4d18d14ca33967ce56235d78518c1ff666730e348a8ca0540f8066ff028?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/98cff4d18d14ca33967ce56235d78518c1ff666730e348a8ca0540f8066ff028?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98cff4d18d14ca33967ce56235d78518c1ff666730e348a8ca0540f8066ff028?s=96&d=mm&r=g","caption":"Viola Hoppe"}}]}},"views":86,"_links":{"self":[{"href":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/wp-json\/wp\/v2\/posts\/19649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/wp-json\/wp\/v2\/comments?post=19649"}],"version-history":[{"count":16,"href":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/wp-json\/wp\/v2\/posts\/19649\/revisions"}],"predecessor-version":[{"id":19676,"href":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/wp-json\/wp\/v2\/posts\/19649\/revisions\/19676"}],"wp:attachment":[{"href":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/wp-json\/wp\/v2\/media?parent=19649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/wp-json\/wp\/v2\/categories?post=19649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/de.meviy.misumi-ec.com\/info\/de\/wp-json\/wp\/v2\/tags?post=19649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}